{"id":15213,"date":"2021-10-26T17:03:20","date_gmt":"2021-10-26T21:03:20","guid":{"rendered":"https:\/\/intosai.nclud.com\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/"},"modified":"2023-05-07T13:44:54","modified_gmt":"2023-05-07T17:44:54","slug":"sais-contribute-to-building-strong-and-resilient-national-public-health-systems","status":"publish","type":"journal-entry","link":"https:\/\/www.intosaijournal.org\/fr\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/","title":{"rendered":"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants"},"content":{"rendered":"\n<p><em>par l&#8217;\u00e9quipe de l&#8217;IDI charg\u00e9e des objectifs de d\u00e9veloppement durable<\/em><\/p>\n\n\n\n<p>Alors que le monde est confront\u00e9 \u00e0 une crise sanitaire mondiale, l&#8217;immense importance de syst\u00e8mes de sant\u00e9 publique solides et r\u00e9silients pour atteindre l&#8217;objectif de d\u00e9veloppement durable n\u00b0 3 des Nations unies (ODD 3) &#8211; assurer une<em>vie saine et promouvoir le bien-\u00eatre de tous \u00e0 tout \u00e2ge &#8211; n&#8217;a<\/em>jamais \u00e9t\u00e9 aussi \u00e9vidente. Les institutions sup\u00e9rieures de contr\u00f4le (ISC) ont un r\u00f4le cl\u00e9 \u00e0 jouer dans la lutte contre les in\u00e9galit\u00e9s croissantes lors de telles pand\u00e9mies et dans la garantie que les segments vuln\u00e9rables de la population ne sont pas laiss\u00e9s pour compte.<\/p>\n\n\n\n<p>\u00c0 cette fin, l&#8217;initiative de d\u00e9veloppement de l&#8217;INTOSAI (IDI), en collaboration avec les secr\u00e9tariats r\u00e9gionaux et le Comit\u00e9 de partage des connaissances et des services de la connaissance (KSC), soutient un audit de performance coop\u00e9ratif li\u00e9 aux \u00e9l\u00e9ments suivants  <a href=\"https:\/\/www.un.org\/sustainabledevelopment\/health\/\">Objectif 3.d des ODD<\/a>  (<em>renforcer la capacit\u00e9 de tous les pays, en particulier des pays en d\u00e9veloppement, en mati\u00e8re d&#8217;alerte pr\u00e9coce, de r\u00e9duction des risques et de gestion des risques sanitaires nationaux et mondiaux<\/em>). L&#8217;\u00e9quipe de l&#8217;Organisation mondiale de la sant\u00e9 (OMS) charg\u00e9e de la r\u00e9silience des services de sant\u00e9 apporte un soutien technique \u00e0 cette initiative. Ce contr\u00f4le coop\u00e9ratif peut avoir un impact \u00e0 la fois au niveau national et r\u00e9gional, car les rapports de contr\u00f4le de plusieurs ISC d&#8217;une r\u00e9gion donneront une image compl\u00e8te de l&#8217;\u00e9tat de la mise en \u0153uvre de l&#8217;ODD 3.d.<\/p>\n\n\n\n<p>Afin de renforcer la capacit\u00e9 des ISC \u00e0 r\u00e9aliser ces audits, l&#8217;IDI a d\u00e9velopp\u00e9 une plateforme int\u00e9gr\u00e9e de formation et d&#8217;aide \u00e0 l&#8217;audit comprenant quatre \u00e9l\u00e9ments : contenu de la formation (unit\u00e9s asynchrones et classes synchrones), apprentissage social (forums de discussion, parkings, caf\u00e9s, webinaires et banque de questions d&#8217;audit), autres ressources (biblioth\u00e8que, liens audio et vid\u00e9o, et liens vers d&#8217;autres cours), et aide \u00e0 l&#8217;audit (retour d&#8217;information et aide \u00e0 chaque \u00e9tape de l&#8217;audit). En plus de l&#8217;\u00e9quipe de l&#8217;IDI, dix-neuf mentors sont engag\u00e9s pour apporter ce soutien.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.idi.no\/work-streams\/relevant-sais\/auditing-sdgs\/audit-sdgs-implementation\/cooperative-audit-sdg-implementation\/sdg-3-d\">Trente-neuf ISC<\/a> de cinq r\u00e9gions participent aux audits 3.d, et la plupart des \u00e9quipes sont actuellement \u00e0 la fin de la phase de planification. Les rapports devraient \u00eatre achev\u00e9s vers la fin du premier trimestre 2022.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu&#8217;est-ce que la r\u00e9silience des syst\u00e8mes de sant\u00e9 publique ?  <\/strong><\/h2>\n\n\n\n<p>Les syst\u00e8mes de sant\u00e9 publique r\u00e9silients att\u00e9nuent les effets des \u00e9v\u00e9nements perturbateurs, s&#8217;y pr\u00e9parent, y r\u00e9pondent et s&#8217;en remettent tout en continuant \u00e0 fournir des services de sant\u00e9 essentiels, et ils s&#8217;appuient sur leur exp\u00e9rience pour apporter des am\u00e9liorations. Pour parvenir \u00e0 la r\u00e9silience, il faut adopter une approche multidimensionnelle et globale des urgences de sant\u00e9 publique aux niveaux politique, op\u00e9rationnel et de la prestation de services, notamment en renfor\u00e7ant les fonctions essentielles de la sant\u00e9 publique. Selon l&#8217;<a href=\"https:\/\/apps.who.int\/iris\/bitstream\/handle\/10665\/272597\/9789241514088-eng.pdf?sequence=1&amp;isAllowed=y\">OMS<\/a>, ces fonctions comprennent par exemple la surveillance, la protection et la promotion de la sant\u00e9, et la pr\u00e9paration \u00e0 la sant\u00e9 publique.<\/p>\n\n\n\n<p>Les syst\u00e8mes de sant\u00e9 publique r\u00e9silients alignent &#8220;la planification des urgences sanitaires sur la strat\u00e9gie plus large du secteur de la sant\u00e9 et vice versa, y compris les budgets appropri\u00e9s et les cadres de suivi et d&#8217;\u00e9valuation pour les interventions planifi\u00e9es et impr\u00e9vues&#8221;<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/34331439\/\">(Mustafa et al., 2021<\/a>).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment les ISC peuvent-elles effectuer des contr\u00f4les efficaces sur l&#8217;ODD 3.d ?  <\/strong><\/h2>\n\n\n\n<p>Bien que la r\u00e9silience des syst\u00e8mes de sant\u00e9 publique comporte de nombreuses dimensions, les audits 3.d se concentrent sur celles qui sont incluses dans cet objectif sp\u00e9cifique. Lors de leurs contr\u00f4les 3.d, les ISC peuvent examiner comment les gouvernements renforcent leur capacit\u00e9 \u00e0 effectuer les t\u00e2ches suivantes (en fonction du contexte national et des risques) :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9voir, pr\u00e9venir et pr\u00e9parer les urgences en mati\u00e8re de sant\u00e9 publique<\/li>\n\n\n\n<li>S&#8217;adapter, absorber et r\u00e9pondre aux urgences en mati\u00e8re de sant\u00e9 publique<\/li>\n\n\n\n<li>Maintenir les services de sant\u00e9 essentiels en cas d&#8217;urgence<\/li>\n<\/ul>\n\n\n\n<p>Les ISC devraient se concentrer sur la coh\u00e9rence et l&#8217;int\u00e9gration des politiques au sein du gouvernement, ainsi que sur la mesure dans laquelle le gouvernement a impliqu\u00e9 diverses parties prenantes dans ses efforts. L&#8217;un des principes de l&#8217;Agenda 2030 des Nations unies est que tous les processus de mise en \u0153uvre des ODD soient participatifs et inclusifs. Les parties prenantes comprennent tous les niveaux et secteurs du gouvernement, la soci\u00e9t\u00e9 civile et le secteur priv\u00e9, les membres du parlement et les institutions nationales des droits de l&#8217;homme.<\/p>\n\n\n\n<p>L&#8217;engagement des parties prenantes est \u00e9troitement li\u00e9 \u00e0 un autre principe important qui sous-tend les audits 3.d : &#8220;ne laisser personne de c\u00f4t\u00e9&#8221;. La pauvret\u00e9 et les in\u00e9galit\u00e9s peuvent emp\u00eacher les groupes vuln\u00e9rables de participer aux progr\u00e8s des ODD et d&#8217;en b\u00e9n\u00e9ficier. Afin d&#8217;\u00e9valuer les efforts d\u00e9ploy\u00e9s par les gouvernements pour ne laisser personne de c\u00f4t\u00e9 dans la mise en \u0153uvre de l&#8217;ODD 3.d, les ISC peuvent poser des questions telles que :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comment le gouvernement identifie-t-il les groupes vuln\u00e9rables ?<\/li>\n\n\n\n<li>Pourquoi ces groupes sont-ils laiss\u00e9s pour compte ?<\/li>\n\n\n\n<li>Quelles sont les sources de donn\u00e9es d\u00e9sagr\u00e9g\u00e9es disponibles sur ces groupes et quelles sont les lacunes en mati\u00e8re de donn\u00e9es ?<\/li>\n\n\n\n<li>Que fait le gouvernement pour d\u00e9terminer les besoins de ces groupes et les soutenir ?<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment les ISC peuvent-elles s&#8217;assurer que leurs contr\u00f4les renforcent la r\u00e9silience des syst\u00e8mes de sant\u00e9 publique ?<\/strong><\/h2>\n\n\n\n<p>Comme le souligne le <a href=\"https:\/\/www.idi.no\/elibrary\/relevant-sais\/auditing-sustainable-development-goals-programme\/isam\/1089-isam-idi-s-sdg-audit-model\">mod\u00e8le d&#8217;audit des ODD (ISAM) de l&#8217;IDI<\/a>, les ISC devraient se concentrer sur l&#8217;impact \u00e0 tous les stades de leurs audits des ODD, y compris lors de la conception, de la r\u00e9alisation et de l&#8217;\u00e9tablissement de rapports sur les audits. Le guide comprend des questions pratiques sur l&#8217;impact de l&#8217;audit que les ISC doivent prendre en consid\u00e9ration tout au long du processus.<\/p>\n\n\n\n<p>Apr\u00e8s avoir publi\u00e9 leur rapport d&#8217;audit, les ISC peuvent prendre d&#8217;autres mesures pour renforcer l&#8217;impact de l&#8217;audit :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Examiner les mesures correctives prises par les parties responsables sur la base des r\u00e9sultats de l&#8217;audit. En fonction de leur mandat, de leurs pratiques de contr\u00f4le et de leurs capacit\u00e9s, les ISC peuvent rencontrer les dirigeants des entit\u00e9s contr\u00f4l\u00e9es, demander des rapports d&#8217;avancement ou effectuer des contr\u00f4les de suivi.<\/li>\n\n\n\n<li>Communiquer les messages cl\u00e9s de l&#8217;audit aux niveaux national, r\u00e9gional et international, notamment par le biais de communiqu\u00e9s de presse, de la participation \u00e0 des \u00e9v\u00e9nements et des m\u00e9dias sociaux.<\/li>\n\n\n\n<li>Cr\u00e9er des coalitions de parties prenantes afin de favoriser un fort sentiment d&#8217;appropriation des travaux et des recommandations de l&#8217;ISC.<\/li>\n<\/ul>\n\n\n\n<p>Lors de r\u00e9centes r\u00e9unions des dirigeants des ISC et des parties prenantes de l&#8217;Organisation arabe des ISC (ARABOSAI), de l&#8217;Organisation asiatique des ISC (ASOSAI), de l&#8217;Association du Pacifique des ISC (PASAI) et de l&#8217;Organisation des ISC des Cara\u00efbes (CAROSAI), les parties prenantes externes ont affirm\u00e9 la contribution de ces audits \u00e0 l&#8217;am\u00e9lioration de la r\u00e9silience des syst\u00e8mes de sant\u00e9 publique et de leur capacit\u00e9 \u00e0 r\u00e9pondre aux crises \u00e0 venir.<\/p>\n\n\n\n<p>En entreprenant ces contr\u00f4les au milieu de la crise sanitaire mondiale actuelle, les ISC d\u00e9montrent aux citoyens, aux d\u00e9cideurs et aux parties prenantes externes qu&#8217;elles peuvent r\u00e9pondre efficacement \u00e0 des environnements changeants et \u00e0 des risques \u00e9mergents. Pour plus d&#8217;informations sur l&#8217;audit de l&#8217;ODD 3.d, <a href=\"https:\/\/www.idi.no\/work-streams\/relevant-sais\/auditing-sdgs\/audit-sdgs-implementation\/cooperative-audit-sdg-implementation\/sdg-3-d\">cliquez ici.<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>&#8220;Travailler en tant que mentor pour ce contr\u00f4le coop\u00e9ratif ne m&#8217;a pas seulement aid\u00e9 \u00e0 me d\u00e9velopper professionnellement et personnellement, mais m&#8217;a aussi aid\u00e9 \u00e0 comprendre profond\u00e9ment pourquoi le travail des ISC est important et comment nous pouvons contribuer \u00e0 la vie des citoyens. Cette mission m&#8217;a appris l&#8217;importance de couvrir les aspects de l&#8217;approche de l&#8217;ensemble du gouvernement et de l&#8217;inclusivit\u00e9 dans le contr\u00f4le de performance pour avoir un plus grand impact.&#8221;<\/em><\/p>\n<cite>Sonam Wnagmo, SAI Bhoutan<\/cite><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le monde est confront\u00e9 \u00e0 une crise sanitaire mondiale, l&#8217;immense importance de syst\u00e8mes de sant\u00e9 publique solides et r\u00e9silients pour atteindre l&#8217;objectif de d\u00e9veloppement durable n\u00b0 3 (ODD 3) des Nations unies &#8211; assurer une vie saine et promouvoir le bien-\u00eatre de tous \u00e0 tout \u00e2ge &#8211; n&#8217;a jamais \u00e9t\u00e9 aussi \u00e9vidente. Les institutions sup\u00e9rieures de contr\u00f4le (ISC) ont un r\u00f4le cl\u00e9 \u00e0 jouer dans la lutte contre les in\u00e9galit\u00e9s croissantes lors de telles pand\u00e9mies et dans la garantie que les segments vuln\u00e9rables de la population ne sont pas laiss\u00e9s pour compte. \u00c0 cette fin, l&#8217;Initiative de d\u00e9veloppement de l&#8217;INTOSAI (IDI), en collaboration avec les secr\u00e9tariats r\u00e9gionaux et le Comit\u00e9 de partage des connaissances et des services de&#8230;<\/p>\n","protected":false},"author":53,"featured_media":7631,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[2069,2112],"content-tags":[1819,858,1786,1780,1899,1804,1929],"country":[],"region":[],"section":[2639],"coauthors":[],"class_list":["post-15213","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-a-linterieur-de-lintosai","journal-categories-automne-2021","content-tags-audits-cooperatifs","content-tags-covid-19-fr","content-tags-idi-fr","content-tags-objectif-intosai-3","content-tags-resilience-fr","content-tags-sdgs-fr","content-tags-soins-de-sante","section-inside-intosai-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Alors que le monde est confront\u00e9 \u00e0 une crise sanitaire mondiale, l&#039;immense importance de syst\u00e8mes de sant\u00e9 publique solides et r\u00e9silients pour atteindre l&#039;objectif de d\u00e9veloppement durable n\u00b0 3 (ODD 3) des Nations unies - assurer une vie saine et promouvoir le bien-\u00eatre de tous \u00e0 tout \u00e2ge - n&#039;a jamais \u00e9t\u00e9 aussi \u00e9vidente. Les institutions sup\u00e9rieures de contr\u00f4le (ISC) ont un r\u00f4le cl\u00e9 \u00e0 jouer dans la lutte contre les in\u00e9galit\u00e9s croissantes lors de telles pand\u00e9mies et dans la garantie que les segments vuln\u00e9rables de la population ne sont pas laiss\u00e9s pour compte. \u00c0 cette fin, l&#039;Initiative de d\u00e9veloppement de l&#039;INTOSAI (IDI), en collaboration avec les secr\u00e9tariats r\u00e9gionaux et le Comit\u00e9 de partage des connaissances et des services de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-07T17:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"804\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"INTOSAI Development Initiative\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/\",\"url\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/\",\"name\":\"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg\",\"datePublished\":\"2021-10-26T21:03:20+00:00\",\"dateModified\":\"2023-05-07T17:44:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage\",\"url\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg\",\"contentUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg\",\"width\":804,\"height\":482},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/","og_locale":"fr_FR","og_type":"article","og_title":"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal","og_description":"Alors que le monde est confront\u00e9 \u00e0 une crise sanitaire mondiale, l'immense importance de syst\u00e8mes de sant\u00e9 publique solides et r\u00e9silients pour atteindre l'objectif de d\u00e9veloppement durable n\u00b0 3 (ODD 3) des Nations unies - assurer une vie saine et promouvoir le bien-\u00eatre de tous \u00e0 tout \u00e2ge - n'a jamais \u00e9t\u00e9 aussi \u00e9vidente. Les institutions sup\u00e9rieures de contr\u00f4le (ISC) ont un r\u00f4le cl\u00e9 \u00e0 jouer dans la lutte contre les in\u00e9galit\u00e9s croissantes lors de telles pand\u00e9mies et dans la garantie que les segments vuln\u00e9rables de la population ne sont pas laiss\u00e9s pour compte. \u00c0 cette fin, l'Initiative de d\u00e9veloppement de l'INTOSAI (IDI), en collaboration avec les secr\u00e9tariats r\u00e9gionaux et le Comit\u00e9 de partage des connaissances et des services de...","og_url":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/","og_site_name":"INTOSAI Journal","article_modified_time":"2023-05-07T17:44:54+00:00","og_image":[{"width":804,"height":482,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Written by":"INTOSAI Development Initiative"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/","url":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/","name":"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg","datePublished":"2021-10-26T21:03:20+00:00","dateModified":"2023-05-07T17:44:54+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#primaryimage","url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg","contentUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2023\/02\/SDG-3.d.jpg","width":804,"height":482},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/journal-entry\/sais-contribute-to-building-strong-and-resilient-national-public-health-systems\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les ISC contribuent \u00e0 la mise en place de syst\u00e8mes nationaux de sant\u00e9 publique solides et r\u00e9sistants"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/15213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/users\/53"}],"version-history":[{"count":3,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/15213\/revisions"}],"predecessor-version":[{"id":15225,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-entry\/15213\/revisions\/15225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/media\/7631"}],"wp:attachment":[{"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/media?parent=15213"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/journal-categories?post=15213"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/content-tags?post=15213"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/country?post=15213"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/region?post=15213"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/section?post=15213"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/fr\/wp-json\/wp\/v2\/coauthors?post=15213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}