{"id":34619,"date":"2025-04-16T17:13:50","date_gmt":"2025-04-16T21:13:50","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=34619"},"modified":"2025-04-16T17:15:38","modified_gmt":"2025-04-16T21:15:38","slug":"pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores","status":"publish","type":"journal-entry","link":"https:\/\/www.intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/","title":{"rendered":"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores"},"content":{"rendered":"\n<p>Autor: Iniciativa de Desarrollo de la INTOSAI<\/p>\n\n\n\n<p>Las Entidades Fiscalizadoras Superiores (EFS) tienen como objetivo marcar la diferencia en la vida de los ciudadanos. Sin embargo, para las EFS que operan en contextos desafiantes, materializar esta gran meta puede no resultar siempre tan obvio. En 2018, la Iniciativa de Desarrollo de la INTOSAI (IDI), la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Inglesa (AFROSAI-E) y la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Francesa (CREFIAF) dise\u00f1aron un modelo revolucionario de apoyo a las EFS que operan en contextos complejos y dif\u00edciles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"647\" height=\"431\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP.jpg\" alt=\"\" class=\"wp-image-34594\" style=\"width:815px;height:auto\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP.jpg 647w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP-300x200.jpg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP-193x128.jpg 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP-310x206.jpg 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP_APP-467x310.jpg 467w\" sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><figcaption class=\"wp-element-caption\">Fuente: Iniciativa de Desarrollo de INTOSAI<\/figcaption><\/figure>\n\n\n\n<p>TEste innovador programa eman\u00f3 de la Convocatoria Global de Propuestas (<em>Global Call for Proposals<\/em>; GCP) Nivel 2 y est\u00e1 destinado a atender las necesidades espec\u00edficas de las EFS en entornos desafiantes. El programa ha logrado impulsar unos avances notables, superando muchos desaf\u00edos y generando valiosas lecciones para futuras intervenciones de creaci\u00f3n de capacidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un enfoque totalmente nuevo<\/h3>\n\n\n\n<p>Una caracter\u00edstica clave del Programa de Asociaci\u00f3n Acelerada de Apoyo entre Pares (<em>Partenariat d\u2019Appui Acc\u00e9l\u00e9r\u00e9 par les Pairs\u201d\/Accelerated Peer Support Programme<\/em>; PAP-APP) es el uso que hace del apoyo entre pares y las asociaciones. Frente a los modelos tradicionales de capacitaci\u00f3n, el PAP-APP aprovecha, por un lado, la experiencia de las EFS con un mayor grado de efectividad organizativa y, por otro, la de los organismos regionales para prestar un apoyo personalizado a EFS con menor efectividad organizativa.<\/p>\n\n\n\n<p>Al promover la colaboraci\u00f3n y el aprendizaje mutuo, el programa materializa el lema de la INTOSAI: \u201c<em>La experiencia mutua beneficia a todos<\/em>\u201d. Este novedoso enfoque permiti\u00f3 a once EFS de una serie de pa\u00edses, a saber, Eritrea, Gambia, Guinea, la Rep\u00fablica Democr\u00e1tica del Congo, Madagascar, N\u00edger, Sierra Leona, Somalia, Sud\u00e1n del Sur, Togo y Zimbabue, implementar planes estrat\u00e9gicos, fortalecer la planificaci\u00f3n operativa, el monitoreo y la presentaci\u00f3n de informes, y realizar auditor\u00edas de impacto a trav\u00e9s de diversos tipos de ayuda.<\/p>\n\n\n\n<p>En sus inicios, las ambiciosas metas del programa PAP-APP plantearon dudas sobre su viabilidad. Debido a que su misi\u00f3n consist\u00eda en superar problem\u00e1ticas muy arraigadas en unos contextos complejos y dif\u00edciles, el \u00e9xito de la iniciativa depend\u00eda de varios factores cr\u00edticos, como el apoyo continuado de los donantes, unas asociaciones entre pares efectivas y la capacidad de adaptarse a los diversos contextos locales. Aunque se trataba de retos importantes, el dise\u00f1o del programa -que pone el acento en la colaboraci\u00f3n, la flexibilidad y el enfoque estrat\u00e9gico- proporcion\u00f3 una base s\u00f3lida para su \u00e9xito final. Durante todos estos a\u00f1os, el PAP-APP ha demostrado que, a trav\u00e9s de la combinaci\u00f3n adecuada de recursos y compromiso, es posible avanzar de manera sustancial en la mejora de las capacidades de las EFS, incluso en los contextos m\u00e1s desafiantes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Creaci\u00f3n de capacidades consistentes<\/h3>\n\n\n\n<p>Una de las piedras angulares del programa PAP-APP ha sido centrarse en la creaci\u00f3n de capacidades tanto de las EFS como de los proveedores del apoyo. Solo en 2024, m\u00e1s de 290 de estos proveedores de apoyo a las EFS y a su personal participaron en iniciativas de creaci\u00f3n de capacidades del programa. Herramientas como la matriz de competencias o los modelos de capacitaci\u00f3n h\u00edbrida fueron fundamentales a la hora de dotar al personal de las EFS y a sus pares de las habilidades necesarias para ejecutar auditor\u00edas complejas y afrontar los retos de gobernanza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Resultados positivos de evaluaciones externas<\/h3>\n\n\n\n<p>Una evaluaci\u00f3n independiente del programa, realizada en 2024 por Ernst &amp; Young-Suecia, elogi\u00f3 el dise\u00f1o y los resultados del programa. El correspondiente informe destac\u00f3 el papel del PAP-APP en la mejora del apoyo entre pares, el desarrollo de herramientas de gesti\u00f3n estrat\u00e9gica y la alineaci\u00f3n con los Objetivos de Desarrollo Sostenible (ODS). Entre los principales logros destacan el aumento en la participaci\u00f3n de pares (en 2024, 15 EFS consolidadas ofrecieron su apoyo a las 11 EFS del PAP-APP) y los grandes avances en la gesti\u00f3n del cambio estrat\u00e9gico y la calidad de las auditor\u00edas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Impacto de los proyectos nacionales<\/h3>\n\n\n\n<p>El alcance del PAP-APP abarca una gran variedad de contextos, gracias a proyectos adaptados a cada pa\u00eds y que generan beneficios tangibles. A continuaci\u00f3n, se resumen algunos de los logros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Madagascar recibi\u00f3 fondos asignados de USAID. El proyecto est\u00e1 brindando apoyo a la EFS en materia de controles jurisdiccionales, fortalecimiento del marco jur\u00eddico, mejora de la comunicaci\u00f3n, gesti\u00f3n estrat\u00e9gica, gobernanza interna, suministro de herramientas digitales y software, as\u00ed como en la promoci\u00f3n de la igualdad de g\u00e9nero y la diversidad.<\/li>\n\n\n\n<li>Sud\u00e1n del Sur recibi\u00f3 financiaci\u00f3n de la Embajada de Noruega en Nairobi. El Proyecto de Cambio Estrat\u00e9gico de la EFS nacional sirvi\u00f3 para reforzar sus capacidades de auditor\u00eda financiera, de cumplimiento y de rendimiento y completar as\u00ed las auditor\u00edas pendientes.<\/li>\n\n\n\n<li>Eritrea, gracias a fondos del Banco Africano de Desarrollo, experiment\u00f3 una mejora en su planificaci\u00f3n estrat\u00e9gica. Adem\u00e1s, recibi\u00f3 el apoyo de formadores locales en los \u00e1mbitos de auditor\u00eda financiera, auditor\u00eda de rendimiento, auditor\u00eda de sistemas inform\u00e1ticos y aseguramiento de la calidad, as\u00ed como en la inclusi\u00f3n de g\u00e9nero para fomentar el desarrollo de capacidades a largo plazo.<\/li>\n\n\n\n<li>En Gambia, las asociaciones entre pares ayudaron a optimizar las metodolog\u00edas de auditor\u00eda y la planificaci\u00f3n operativa, lo que permiti\u00f3 llevar a cabo auditor\u00edas oportunas y de gran impacto, como la auditor\u00eda de las cuentas p\u00fablicas consolidadas de 2020.\u00a0<\/li>\n\n\n\n<li>En Zimbabue, el programa supuso la realizaci\u00f3n de revisiones estrat\u00e9gicas y el desarrollo de planes operativos, que mejoraron las pr\u00e1cticas de gobernanza y rendici\u00f3n de cuentas. La EFS de Suecia tambi\u00e9n proporcion\u00f3 apoyo t\u00e9cnico en el marco de cooperaci\u00f3n del PAP-APP.\u00a0\u00a0\u00a0<\/li>\n\n\n\n<li>En Sierra Leona, el programa llev\u00f3 al fortalecimiento de la gesti\u00f3n estrat\u00e9gica. Esto inclu\u00eda revisiones de la gesti\u00f3n y el desarrollo de los procesos de elaboraci\u00f3n de estrategias, planificaci\u00f3n operativa &amp; monitoreo y presentaci\u00f3n de informes.<\/li>\n\n\n\n<li>En Guinea y Togo, una serie de proyectos a peque\u00f1a escala se centraron en auditor\u00edas basadas en cuestiones de g\u00e9nero y en la gesti\u00f3n estrat\u00e9gica para generar conclusiones pr\u00e1cticas y fortalecer los procesos de planificaci\u00f3n. Adem\u00e1s, Guinea ha recibido apoyo para la auditor\u00eda de las actividades de los contables p\u00fablicos a efectos de la disciplina presupuestaria.<\/li>\n\n\n\n<li>En Somalia, el amplio apoyo prestado mejor\u00f3 los procesos de presentaci\u00f3n de informes para las auditor\u00edas financieras y de cumplimiento, a la vez que permiti\u00f3 desarrollar iniciativas de capacitaci\u00f3n profesional para el personal de la EFS.<\/li>\n\n\n\n<li>En la Rep\u00fablica Democr\u00e1tica del Congo, un proyecto financiado por NORAD condujo a mejoras en las TIC, el desarrollo de estrategias de comunicaci\u00f3n y el aumento de las capacidades de auditor\u00eda.<\/li>\n\n\n\n<li>En N\u00edger, a pesar de las interrupciones que sufri\u00f3 el apoyo desde la toma del poder por los militares en julio de 2023, la EFS recibi\u00f3 asistencia para la gesti\u00f3n estrat\u00e9gica, la participaci\u00f3n de las partes interesadas y las auditor\u00edas de diversidad de g\u00e9nero e inclusividad.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Desaf\u00edos<\/h3>\n\n\n\n<p>Al margen de sus \u00e9xitos, el PAP-APP tuvo que hacer frente a muchos desaf\u00edos, entre ellos la adaptaci\u00f3n al contexto local. Las diferencias en los contextos pol\u00edticos, culturales e institucionales exig\u00edan una adaptaci\u00f3n continua del apoyo. Entre otras medidas, la capacitaci\u00f3n en Adaptaci\u00f3n Iterativa Guiada por Problemas (PDIA, por sus siglas en ingl\u00e9s) y la participaci\u00f3n a largo plazo de los pares resultaron vitales para superar estos desaf\u00edos.<\/p>\n\n\n\n<p>Por otra parte, muchas de las EFS siguen careciendo de infraestructura y recursos suficientes, lo que deja patente la necesidad de un compromiso adicional por parte de los donantes para atender las necesidades a largo plazo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lecciones para programas futuros<\/h3>\n\n\n\n<p>La experiencia adquirida con el PAP-APP es muy valiosa para iniciativas similares. Tras la finalizaci\u00f3n del programa, entre las principales lecciones aprendidas destacan las siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Flexibilidad en el dise\u00f1o:<\/strong> Personalizar el apoyo conforme a las necesidades espec\u00edficas de las EFS y mantener canales de comunicaci\u00f3n abiertos fomenta la confianza y la pertinencia.<\/li>\n\n\n\n<li><strong>Efectividad del apoyo entre pares:<\/strong> El apoyo entre pares representa una manera muy efectiva de abordar las necesidades de creaci\u00f3n de capacidades de las EFS. Pero para que tenga \u00e9xito, necesita una buena gesti\u00f3n, financiaci\u00f3n y coordinaci\u00f3n.\u00a0<\/li>\n\n\n\n<li><strong>Institucionalizaci\u00f3n de las mejores pr\u00e1cticas:<\/strong> Los procesos de planificaci\u00f3n estrat\u00e9gica, monitoreo y presentaci\u00f3n de informes son fundamentales para la efectividad de una EFS. La incorporaci\u00f3n de estos procesos precisa de una orientaci\u00f3n constante.<\/li>\n\n\n\n<li><strong>Implicaci\u00f3n y compromiso efectivos de los donantes:<\/strong> El establecimiento de asociaciones fiables y la armonizaci\u00f3n de las estrategias de financiaci\u00f3n suponen dos factores cr\u00edticos para una sostenibilidad a largo plazo. Adem\u00e1s, la implicaci\u00f3n y la coordinaci\u00f3n continuas de los donantes resultan \u00fatiles para elevar el perfil de las EFS y evitar la duplicaci\u00f3n del apoyo que se les presta.<\/li>\n<\/ul>\n\n\n\n<p>Dado que el programa PAP-APP concluy\u00f3 en 2024, queremos expresar nuestro agradecimiento a todas las partes interesadas, en especial a los pares proveedores de apoyo y a los donantes de fondos. El legado del programa evidencia el poder transformador de la colaboraci\u00f3n entre pares y la importancia de las estrategias de adaptaci\u00f3n en la creaci\u00f3n de capacidades. En su af\u00e1n por seguir innovando y compartiendo las lecciones aprendidas, el programa PAP-APP y sus socios est\u00e1n sentando unas s\u00f3lidas bases para el futuro de las EFS a escala global.&nbsp;<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre el PAP-APP, visite: <a href=\"https:\/\/www.idi.no\/bilateral-support\/pap-app\">Accelerated Peer-support Partnership (PAP-APP)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Entidades Fiscalizadoras Superiores (EFS) tienen como objetivo marcar la diferencia en la vida de los ciudadanos. Sin embargo, para las EFS que operan en contextos desafiantes, materializar esta gran meta puede no resultar siempre tan obvio. En 2018, la Iniciativa de Desarrollo de la INTOSAI (IDI), la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Inglesa (AFROSAI-E) y la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Francesa (CREFIAF) dise\u00f1aron un modelo revolucionario de apoyo a las EFS que operan en contextos complejos y dif\u00edciles.<\/p>\n","protected":false},"author":53,"featured_media":34603,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4043],"content-tags":[954,982,984,1135,1221],"country":[3702,4093,4094,3014,4095,2855,3179,4096],"region":[1337,2682],"section":[1345],"coauthors":[3332],"class_list":["post-34619","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q1-2025-es","content-tags-audit-impact-es","content-tags-capacity-building-es","content-tags-capacity-development-es","content-tags-lessons-learned-es","content-tags-spotlight-on-capacity-building-es","country-democratic-republic-of-the-congo-es","country-eritrea-es","country-guinea-es","country-madagascar-es","country-niger-es","country-sierra-leone-es","country-somalia-es","country-south-sudan-es","region-afrosai-es","region-afrosai-e-es","section-spotlight-on-capacity-building-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Las Entidades Fiscalizadoras Superiores (EFS) tienen como objetivo marcar la diferencia en la vida de los ciudadanos. Sin embargo, para las EFS que operan en contextos desafiantes, materializar esta gran meta puede no resultar siempre tan obvio. En 2018, la Iniciativa de Desarrollo de la INTOSAI (IDI), la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Inglesa (AFROSAI-E) y la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Francesa (CREFIAF) dise\u00f1aron un modelo revolucionario de apoyo a las EFS que operan en contextos complejos y dif\u00edciles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T21:15:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"INTOSAI Development Initiative\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/\",\"url\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/\",\"name\":\"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png\",\"datePublished\":\"2025-04-16T21:13:50+00:00\",\"dateModified\":\"2025-04-16T21:15:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage\",\"url\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png\",\"contentUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png\",\"width\":1326,\"height\":880,\"caption\":\"Fuente: Iniciativa de Desarrollo de INTOSAI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/","og_locale":"es_ES","og_type":"article","og_title":"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","og_description":"Las Entidades Fiscalizadoras Superiores (EFS) tienen como objetivo marcar la diferencia en la vida de los ciudadanos. Sin embargo, para las EFS que operan en contextos desafiantes, materializar esta gran meta puede no resultar siempre tan obvio. En 2018, la Iniciativa de Desarrollo de la INTOSAI (IDI), la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Inglesa (AFROSAI-E) y la Organizaci\u00f3n Africana de Entidades Fiscalizadoras Superiores de Habla Francesa (CREFIAF) dise\u00f1aron un modelo revolucionario de apoyo a las EFS que operan en contextos complejos y dif\u00edciles.","og_url":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/","og_site_name":"INTOSAI Journal","article_modified_time":"2025-04-16T21:15:38+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"7 minutes","Written by":"INTOSAI Development Initiative"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/","url":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/","name":"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png","datePublished":"2025-04-16T21:13:50+00:00","dateModified":"2025-04-16T21:15:38+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#primaryimage","url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png","contentUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/PAP-APP-Cover-Q1-2025.png","width":1326,"height":880,"caption":"Fuente: Iniciativa de Desarrollo de INTOSAI"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/es\/journal-entry\/pap-app-2018-2024-un-enfoque-revolucionario-para-potenciar-el-impacto-de-las-entidades-fiscalizadoras-superiores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/es\/"},{"@type":"ListItem","position":2,"name":"PAP-APP 2018-2024: un enfoque revolucionario para potenciar el impacto de las Entidades Fiscalizadoras Superiores"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/34619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/users\/53"}],"version-history":[{"count":1,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/34619\/revisions"}],"predecessor-version":[{"id":34621,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-entry\/34619\/revisions\/34621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/media\/34603"}],"wp:attachment":[{"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/media?parent=34619"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/journal-categories?post=34619"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/content-tags?post=34619"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/country?post=34619"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/region?post=34619"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/section?post=34619"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/es\/wp-json\/wp\/v2\/coauthors?post=34619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}