{"id":41771,"date":"2026-06-30T10:30:00","date_gmt":"2026-06-30T14:30:00","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=41771"},"modified":"2026-07-14T11:54:59","modified_gmt":"2026-07-14T15:54:59","slug":"orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung","status":"publish","type":"journal-entry","link":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/","title":{"rendered":"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung"},"content":{"rendered":"\n<p><strong>Autor: Oberste Rechnungskontrollbeh\u00f6rde der Union Myanmar<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Einleitung<\/strong><\/h2>\n\n\n\n<p>Vor dem Hintergrund der laufenden politischen, wirtschaftlichen, sozialen und administrativen Reformen in Myanmar steigen die Erwartungen der \u00d6ffentlichkeit, was die wirksame Nutzung der Ressourcen im b\u00fcrgerschaftlichen Eigentum sowie die solide \u00f6ffentliche Finanzverwaltung durch die Regierung anbelangt.<\/p>\n\n\n\n<p>Ministerien und staatliche Stellen nehmen ihre Aufgaben aktiv wahr, um die nationale Entwicklung zu unterst\u00fctzen sowie die Erwartungen der B\u00fcrgerinnen und B\u00fcrger zu erf\u00fcllen. In diesem Sinne versteht sich die Oberste Rechnungskontrollbeh\u00f6rde der Union (Office of the Auditor General; OAG) als Institution, die \u00f6ffentliche Interessen sch\u00fctzt sowie f\u00f6rdert und dabei nationale Priorit\u00e4ten sowie das Wohlergehen der B\u00fcrgerinnen und B\u00fcrger in den Mittelpunkt ihrer Mission stellt. Als Oberste Rechnungskontrollbeh\u00f6rde (ORKB) spielt sie eine entscheidende Rolle bei der \u00dcberwachung der Umsetzung staatlicher Programme und T\u00e4tigkeiten. Dabei stellt sie sicher, dass diese wie beabsichtigt wirksame Ergebnisse erzielen und zur Verbesserung der \u00f6ffentlichen Finanzverwaltung beitragen. Das OAG ist bestrebt, Pr\u00fcfungen professionell und effizient durchzuf\u00fchren, wobei der Dienst am \u00f6ffentlichen Interesse im Vordergrund steht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pr\u00fcfungsaufgaben des OAG<\/strong><\/h2>\n\n\n\n<p>Die Systeme der \u00f6ffentlichen Finanzverwaltung von Ministerien und Einrichtungen des \u00f6ffentlichen Sektors sowie das Verhalten von Beamtinnen und Beamten m\u00fcssen die Grunds\u00e4tze Rechenschaftspflicht und Transparenz hochhalten. Transparenz bedeutet, dass die \u00d6ffentlichkeit dar\u00fcber informiert wird, wie \u00f6ffentliche Mittel verwendet werden und welche Leistungen Organisationen erbringen. Rechenschaftspflicht bedeutet, dass diejenigen, die f\u00fcr die Verwaltung \u00f6ffentlicher Mittel zust\u00e4ndig sind, f\u00fcr ihr Handeln Rechenschaft ablegen und bei Bedarf Korrekturma\u00dfnahmen ergreifen m\u00fcssen. Diese Grunds\u00e4tze sind unerl\u00e4sslich f\u00fcr eine wirksame und verantwortungsvolle Verwaltung der \u00f6ffentlichen Finanzen.<\/p>\n\n\n\n<p>Gemeinsam mit den regionalen Rechnungskontrollbeh\u00f6rden hat das OAG die Aufgabe, dar\u00fcber zu berichten, inwieweit die zust\u00e4ndigen Personen und Organisationen die \u00f6ffentlichen Gelder, die staatlichen Einrichtungen anvertraut wurden, wirksam eingesetzt haben. Somit \u00fcbt das OAG eine externe Aufsichtsfunktion aus, die von wesentlicher Bedeutung f\u00fcr die St\u00e4rkung des \u00f6ffentlichen Finanzverwaltungssystems ist. In jedem Ministerium und jeder Einrichtung werden die Rechnungsabschl\u00fcsse von den jeweiligen Buchhalterinnen und Buchhaltern erstellt und mit Genehmigung der Leitung ver\u00f6ffentlicht. Das Pr\u00fcfungspersonal ist dann daf\u00fcr zust\u00e4ndig, die Richtigkeit sowie Vollst\u00e4ndigkeit dieser Rechnungsabschl\u00fcsse und der zugeh\u00f6rigen Budgetangaben im Zuge einer Pr\u00fcfung der relevanten Nachweise unter die Lupe zu nehmen. Anschlie\u00dfend muss es einen Best\u00e4tigungsvermerk dar\u00fcber abgeben, ob die Rechnungsabschl\u00fcsse in allen wesentlichen Belangen in \u00dcbereinstimmung mit dem geltenden Rechnungslegungsrahmenwerk ein den tats\u00e4chlichen Verh\u00e4ltnissen entsprechendes Bild vermitteln.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Rechtsrahmen f\u00fcr das Pr\u00fcfwesen<\/strong><\/h2>\n\n\n\n<p>Damit Pr\u00fcferinnen und Pr\u00fcfer ihre Aufgaben erfolgreich erf\u00fcllen k\u00f6nnen, wurde im Jahr&nbsp;2010 das Gesetz \u00fcber die staatliche Finanzkontrolle erlassen und anschlie\u00dfend in den Jahren&nbsp;2013, 2014 und 2018 novelliert. Diese Novellen wurden erlassen, um neuen Bed\u00fcrfnissen sowie Herausforderungen Rechnung zu tragen, und verfolgen das Ziel, die rechtzeitige Aufdeckung sowie \u00dcberwachung von Verschwendung, Schwund, Einbu\u00dfen, Verlust und Missbrauch \u00f6ffentlicher Mittel zu verbessern, die staatliche Zusammenarbeit im Rahmen von Pr\u00fcfungsverfahren zu f\u00f6rdern, das \u00f6ffentliche Interesse zu wahren, die Wirksamkeit der Pr\u00fcfungst\u00e4tigkeiten zu steigern und die Ausrichtung an den Internationalen Normen f\u00fcr Oberste Rechnungskontrollbeh\u00f6rden (ISSAI) sowie an international bew\u00e4hrten Verfahren sicherzustellen.<\/p>\n\n\n\n<p>Das OAG f\u00fchrt seine Pr\u00fcfungen in \u00dcbereinstimmung mit dem Gesetz \u00fcber die staatliche Finanzkontrolle durch. Abschnitt&nbsp;11 des Gesetzes schreibt vor, dass es die Hauptaufgabe der ORKB ist, die Einnahmen- und Ausgabenkonten des Staates zu pr\u00fcfen. Abschnitt&nbsp;11 legt insgesamt 27&nbsp;konkrete Aufgaben fest. Um diese Aufgaben erfolgreich zu erf\u00fcllen, erstellte das OAG eine klare Vision, definierte Aufgaben und formulierte relevante Richtlinien sowie Strategien. Das OAG f\u00fchrt seine Pr\u00fcfungsverfahren kompetent sowie effizient durch. Damit steht es im Einklang mit den Erwartungen der \u00d6ffentlichkeit an gute Regierungsf\u00fchrung und saubere Verwaltung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reform des OAG<\/strong><\/h2>\n\n\n\n<p>Im Rahmen seiner Reformbem\u00fchungen setzte das OAG mehrere wichtige Initiativen um. Dazu geh\u00f6rten die Novellierung des Gesetzes \u00fcber die staatliche Finanzkontrolle zur St\u00e4rkung des Rechtsrahmens, die \u00dcbertragung erweiterter Zust\u00e4ndigkeiten an die Rechnungskontrollbeh\u00f6rden in den Regionen und Staaten sowie an deren Pr\u00fcfungspersonal zur Verbesserung der dezentralen Aufsicht, die Ausarbeitung Strategischer Pl\u00e4ne f\u00fcr die Zeitr\u00e4ume&nbsp;2018\u20132022 und 2023\u20132027, Bem\u00fchungen zur \u00dcbernahme internationaler Normen f\u00fcr die Rechnungslegung und das Pr\u00fcfwesen sowie die Beteiligung an Reforminitiativen im Bereich der \u00f6ffentlichen Finanzverwaltung.<\/p>\n\n\n\n<p>Mit Stand&nbsp;2025 geh\u00f6ren landesweit \u00fcber 410&nbsp;Rechnungskontrollbeh\u00f6rden zum OAG, darunter auf Ebene der Regionen und Staaten sowie die Rechnungskontrollbeh\u00f6rde Nay Pyi Taw. Das OAG ist f\u00fcr die Pr\u00fcfung von 16.304&nbsp;Einrichtungen im ganzen Land zust\u00e4ndig und wird dabei von 3.651&nbsp;Mitarbeiterinnen und Mitarbeiterin im Pr\u00fcfdienst sowie 851&nbsp;Personen mit anderen Funktionen, d.&nbsp;h. einer Gesamtbelegschaft von 4.502&nbsp;Angestellten, unterst\u00fctzt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pr\u00fcfungen der Rechnungsf\u00fchrung und Budgetaufsicht des OAG<\/strong><\/h2>\n\n\n\n<p>Gem\u00e4\u00df den Bestimmungen des Unionsbudgetgesetzes pr\u00fcft das OAG die Einnahmen- und Ausgabenkonten der Union, ob Ma\u00dfnahmen ergriffen wurden, um die im Budgetvoranschlag enthaltenen Einnahmen vollst\u00e4ndig zu erzielen, und ob die im Budgetvoranschlag enthaltenen bewilligten Mittel wirksam verwendet werden. Dar\u00fcber hat es dem h\u00f6chsten Staatsorgan mindestens einmal j\u00e4hrlich sowie anl\u00e4sslich au\u00dfergew\u00f6hnlicher Situationen einen entsprechenden Bericht vorzulegen.<\/p>\n\n\n\n<p>Gem\u00e4\u00df dem Gesetz \u00fcber die staatliche Finanzkontrolle pr\u00fcfen das OAG sowie die Rechnungskontrollbeh\u00f6rden der verschiedenen Ebenen, ob die im Finanzjahr von B\u00fcrgerinnen und B\u00fcrgern, aus anderen Einnahmequellen sowie durch Beihilfen oder Darlehen aus dem Ausland erhaltenen Mittel auf die kosteng\u00fcnstigste, effizienteste und wirkungsvollste Weise zum Wohle der Nation verwendet werden. Zudem beurteilen sie, inwieweit diese Mittel dem \u00f6ffentlichen und nationalen Interesse dienen, und erstellen diesbez\u00fcglich Berichte. Als Pr\u00fcfungskriterien f\u00fcr die Beurteilung anl\u00e4sslich der Pr\u00fcfungen dienen das Unionsbudgetgesetz, die Budgetgesetze der Regionen und Staaten, das nationale Planungsgesetz, das regionale Planungsgesetz, das Unionssteuergesetz, das Gesetz \u00fcber die Staatsschuldenverwaltung sowie relevante Finanzvorschriften, Verordnungen, Bekanntmachungen und Richtlinien zum Budget.<\/p>\n\n\n\n<p>Im Zuge der Berichterstattung \u00fcber Pr\u00fcfungserkenntnisse, die von den festgelegten Kriterien abweichen, wird das Unionsbudget dahingehend bewertet, ob es von den Einrichtungen auf Unionsebene transparent und wirksam verwendet wird. Die gewonnenen Erkenntnisse werden dem h\u00f6chsten Staatsorgan einmal j\u00e4hrlich vorgelegt. In \u00e4hnlicher Weise werden die Budgets der Regionen sowie Staaten anhand ihrer transparenten und effektiven Verwendung durch die Einrichtungen auf regionaler bzw. staatlicher Ebene bewertet. Die Erkenntnisse werden den jeweiligen Regional- bzw. Staatsregierungen vorgelegt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mehr als Pr\u00fcfungen der Rechnungsf\u00fchrung<\/strong><\/h2>\n\n\n\n<p>Bisher f\u00fchrte das OAG Pr\u00fcfungen der Rechnungsf\u00fchrung, Pr\u00fcfungen der Recht- und Ordnungsm\u00e4\u00dfigkeit sowie Wirtschaftlichkeitspr\u00fcfungen durch, um die Wirksamkeit, Effizienz und Wirtschaftlichkeit staatlicher T\u00e4tigkeiten zu beurteilen. Nun wurde sein Pr\u00fcfungsrepertoire um Echtzeitpr\u00fcfungen erweitert, die eine schnellere Aufdeckung von Unregelm\u00e4\u00dfigkeiten in laufenden Verfahren erm\u00f6glichen, sowie um IT-Pr\u00fcfungen, welche die Zuverl\u00e4ssigkeit, Sicherheit und Wirksamkeit staatlicher Informationssysteme bewerten.<\/p>\n\n\n\n<p>Zus\u00e4tzlich zu seiner Pr\u00fcft\u00e4tigkeit erbringt das OAG eine einzigartige Dienstleistung: Es bietet staatlichen Stellen Kommentare sowie Empfehlungen zu Rechnungslegungs- und Finanzangelegenheiten, Finanzvorschriften und -verfahren sowie zum Beschaffungsverfahren, mit dem Ziel, die \u00f6ffentliche Finanzverwaltung zu st\u00e4rken. Diese proaktiven Beratungsleistungen, die auf Anfrage erbracht werden, helfen Stellen, Probleme zu vermeiden, Risiken zu mindern, Ergebnisse zu verbessern und Chancen zu ergreifen, wenn sie neue Richtlinien, Verfahren, Projekte oder sonstige Initiativen ausarbeiten. Zudem wird dadurch die Einhaltung etablierter Richtlinien, Verfahren und Vorschriften sichergestellt.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus bietet das Institut f\u00fcr fortgeschrittene Rechnungslegung und -pr\u00fcfung, das dem OAG unterstellt ist, Schulungen im Bereich Rechnungslegung an, darunter Diplomlehrg\u00e4nge zu den internationalen Rechnungslegungsstandards f\u00fcr den \u00f6ffentlichen Sektor (IPSAS) und den internationalen Rechnungslegungsvorschriften f\u00fcr Unternehmen (IFRS). Auch die Rechnungskontrollbeh\u00f6rden in den Regionen und Staaten halten Basisausbildungen im Bereich Rechnungslegung. Diese Schulungsinitiativen zielen darauf ab, professionelle Buchhalterinnen und Buchhalter auszubilden, die ethische Standards einhalten und so f\u00fcr mehr Transparenz in der Finanzberichterstattung staatlicher Einrichtungen sorgen. Au\u00dferdem absolvierten Mitarbeiterinnen und Mitarbeiter des OAG Schulungen zu ISSAI-basierten Pr\u00fcfungen der Rechnungsf\u00fchrung, damit ihre Pr\u00fcfungen sowie die entsprechende Berichterstattung im Einklang mit internationalen Normen steht. Nach einer landesweiten Einf\u00fchrungsphase und der praktischen Durchf\u00fchrung einiger Pr\u00fcfungen, werden seit dem Finanzjahr&nbsp;2022\/2023 in s\u00e4mtlichen Rechnungskontrollbeh\u00f6rden ISSAI-basierte Pr\u00fcfungen der Rechnungsf\u00fchrung durchgef\u00fchrt. Des Weiteren tr\u00e4gt das OAG zum Ausbau institutioneller Sachkompetenzen bei: Es erstellte f\u00fcr die dem Planungs- und Finanzministerium unterstellte Akademie der \u00f6ffentlichen Finanzverwaltung einen Lehrplan f\u00fcr Rechnungslegung und -pr\u00fcfung und stellte Vortragende f\u00fcr die Wissensvermittlung in diesen F\u00e4chern ab.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/OAG-Myanmar-Q2-2026-Article-1024x576.jpeg\" alt=\"\" class=\"wp-image-41750\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/OAG-Myanmar-Q2-2026-Article-1024x576.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/OAG-Myanmar-Q2-2026-Article-300x169.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/OAG-Myanmar-Q2-2026-Article-768x432.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/OAG-Myanmar-Q2-2026-Article.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Abschlussfeier des Diplomlehrgangs zu den internationalen Rechnungslegungsstandards f\u00fcr den \u00f6ffentlichen Sektor (2.\u00a0Jahrgang, 1.\u00a0Niveau)<\/em>. <em>Quelle: Oberste Rechnungskontrollbeh\u00f6rde der Union Myanmar<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fazit<\/strong><\/h2>\n\n\n\n<p>Pr\u00fcfungen der Rechnungsf\u00fchrung tragen dazu bei, dass \u00f6ffentliche Gelder transparent verwendet werden. Dabei unterst\u00fctzen sie die Korruptionspr\u00e4vention, minimieren Verluste sowie Verschwendung und st\u00e4rken das Vertrauen der \u00d6ffentlichkeit. Folglich f\u00f6rdert Myanmar transparente finanzielle Verfahren, die nachhaltige Entwicklung vorantreiben. Gleichzeitig st\u00e4rken laufende Verbesserungen der Regierungsf\u00fchrung weiterhin die \u00f6ffentliche Finanzverwaltung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor dem Hintergrund der laufenden politischen, wirtschaftlichen, sozialen und administrativen Reformen in Myanmar steigen die Erwartungen der \u00d6ffentlichkeit, was die wirksame Nutzung der Ressourcen im b\u00fcrgerschaftlichen Eigentum sowie die solide \u00f6ffentliche Finanzverwaltung durch die Regierung anbelangt.<\/p>\n","protected":false},"author":86,"featured_media":41759,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4502],"content-tags":[2383,2334,2380,2229,4392,2174],"country":[3158],"region":[2594],"section":[2603],"coauthors":[3438],"class_list":["post-41771","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q2-2026","content-tags-finanzprufung","content-tags-haushalt","content-tags-haushaltsanalyse-de","content-tags-rechenschaftspflicht","content-tags-sai-legal-framework-de","content-tags-transparenz","country-myanmar-2-de","region-asosai-de-2","section-fachartikel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Vor dem Hintergrund der laufenden politischen, wirtschaftlichen, sozialen und administrativen Reformen in Myanmar steigen die Erwartungen der \u00d6ffentlichkeit, was die wirksame Nutzung der Ressourcen im b\u00fcrgerschaftlichen Eigentum sowie die solide \u00f6ffentliche Finanzverwaltung durch die Regierung anbelangt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T15:54:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Office of the Auditor General of the Union Myanmar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/\",\"url\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/\",\"name\":\"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png\",\"datePublished\":\"2026-06-30T14:30:00+00:00\",\"dateModified\":\"2026-07-14T15:54:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage\",\"url\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png\",\"contentUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png\",\"width\":1326,\"height\":880,\"caption\":\"Quelle: Rechnungshof der Union Myanmar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#website\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/www.intosaijournal.org\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/","og_locale":"de_DE","og_type":"article","og_title":"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal","og_description":"Vor dem Hintergrund der laufenden politischen, wirtschaftlichen, sozialen und administrativen Reformen in Myanmar steigen die Erwartungen der \u00d6ffentlichkeit, was die wirksame Nutzung der Ressourcen im b\u00fcrgerschaftlichen Eigentum sowie die solide \u00f6ffentliche Finanzverwaltung durch die Regierung anbelangt.","og_url":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/","og_site_name":"INTOSAI Journal","article_modified_time":"2026-07-14T15:54:59+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"7 minutes","Written by":"Office of the Auditor General of the Union Myanmar"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/","url":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/","name":"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung - INTOSAI Journal","isPartOf":{"@id":"https:\/\/www.intosaijournal.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png","datePublished":"2026-06-30T14:30:00+00:00","dateModified":"2026-07-14T15:54:59+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#primaryimage","url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png","contentUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2026\/06\/Q2-2026-SAI-Myanmar.png","width":1326,"height":880,"caption":"Quelle: Rechnungshof der Union Myanmar"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/orkb-myanmar-staerkere-mechanismen-bei-pruefungen-der-rechnungsfuehrung-fuer-eine-bessere-oeffentliche-finanzverwaltung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/de\/"},{"@type":"ListItem","position":2,"name":"ORKB Myanmar: st\u00e4rkere Mechanismen bei Pr\u00fcfungen der Rechnungsf\u00fchrung f\u00fcr eine bessere \u00f6ffentliche Finanzverwaltung"}]},{"@type":"WebSite","@id":"https:\/\/www.intosaijournal.org\/es\/#website","url":"https:\/\/www.intosaijournal.org\/es\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/www.intosaijournal.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intosaijournal.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.intosaijournal.org\/es\/#organization","name":"INTOSAI Journal","url":"https:\/\/www.intosaijournal.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/www.intosaijournal.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/users\/86"}],"version-history":[{"count":1,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41771\/revisions"}],"predecessor-version":[{"id":41773,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/41771\/revisions\/41773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media\/41759"}],"wp:attachment":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media?parent=41771"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-categories?post=41771"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/content-tags?post=41771"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/country?post=41771"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/region?post=41771"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/section?post=41771"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/coauthors?post=41771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}