{"id":34263,"date":"2025-04-16T16:26:42","date_gmt":"2025-04-16T20:26:42","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=34263"},"modified":"2025-04-16T16:29:11","modified_gmt":"2025-04-16T20:29:11","slug":"greenwashing-der-staatlichen-holzernte-in-polen","status":"publish","type":"journal-entry","link":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/","title":{"rendered":"Greenwashing der staatlichen Holzernte in Polen"},"content":{"rendered":"\n<p>Autor: Iwona Zubrzycka-Wasil, leitende Pr\u00fcferin, Oberste Rechnungskontrollbeh\u00f6rde Polen\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Einleitung<\/strong><\/strong><\/h2>\n\n\n\n<p>Der Oberste Rechnungshof der Republik Polen pr\u00fcfte die Umsetzung eines strategischen Pilotprojekts, der <em>Forest Carbon Farms <\/em>(dt. etwa \u201eWaldkohlenstoffbetriebe\u201c), um dessen Leistung zu \u00fcberpr\u00fcfen und festzustellen, ob die Mittel w\u00e4hrend der Umsetzung durch die Generaldirektion Staatsforste effizient eingesetzt wurden. Bei der Pr\u00fcfung wurde auch untersucht, ob die besten Ergebnisse erzielt werden konnten und ob die Forstgebiete ihre Aktivit\u00e4ten im Rahmen des Projekts korrekt und zuverl\u00e4ssig geplant sowie durchgef\u00fchrt haben.&nbsp;<\/p>\n\n\n\n<p>Die ORKB pr\u00fcfte die T\u00e4tigkeiten des Ministers f\u00fcr Klima und Umwelt, die Generaldirektion Staatsforste und 12 der 25&nbsp;Forstgebiete (von insgesamt 429&nbsp;Gebieten in ganz Polen), die das Pilotprojekt <em>Forest Carbon Farms<\/em> durchf\u00fchrten. Die Pr\u00fcfung bezog sich auf die erste Phase der Projektumsetzung in den Jahren&nbsp;2017 bis 2023.<\/p>\n\n\n\n<p>Die im Jahr\u00a02019 verabschiedete staatliche Strategie zur Weiterentwicklung der Ma\u00dfnahmen in den Bereichen Umwelt und Wasserwirtschaft\u00a02030 sieht unter anderem vor, den Klimawandel durch eine wirksame Verringerung der Treibhausgaskonzentration in der Atmosph\u00e4re, die Verringerung der Kohlendioxidkonzentration und die Bindung von Kohlenstoff in den W\u00e4ldern durch die weitere Umsetzung des im Jahr\u00a02017 gestarteten Projekts <em>Forest Carbon Farms <\/em>zu bek\u00e4mpfen.<\/p>\n\n\n\n<p>L\u00f6sungen und Technologien, die auf die Absorption von Kohlendioxid abzielen, geh\u00f6ren zu den zahlreichen Ma\u00dfnahmen zur Bek\u00e4mpfung des Klimawandels. W\u00e4lder spielen eine entscheidende Rolle bei der nat\u00fcrlichen Absorption von Kohlendioxid (CO<sub>2<\/sub>) aus der Atmosph\u00e4re. Im Jahr\u00a02021 absorbierten die W\u00e4lder Polens insgesamt 22,2\u00a0Millionen Tonnen CO<sub>2<\/sub>, was fast 7\u00a0% der gesamten landesweiten Emissionen ausmachte und dem durchschnittlichen EU-Indikator im Jahr\u00a02019 entsprach.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-1024x683.png\" alt=\"\" class=\"wp-image-34265\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-1024x683.png 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-300x200.png 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-768x512.png 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-1536x1024.png 1536w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-2048x1365.png 2048w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-660x440.png 660w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-1320x880.png 1320w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-193x128.png 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-310x206.png 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.22.17-PM-467x310.png 467w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Nach den kleinen statistischen Jahrb\u00fcchern Polens 2017\u20132023, Statistikamt Polen<\/figcaption><\/figure>\n\n\n\n<p>Die in den ausgew\u00e4hlten 23\u00a0Forstgebieten durchgef\u00fchrten Aktivit\u00e4ten sollten zur Erh\u00f6hung der von den Wald\u00f6kosystemen absorbierten CO<sub>2<\/sub>-Menge beitragen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Projektt\u00e4tigkeiten und erwartete Ergebnisse der <em>Forest Carbon Farms<\/em><\/strong><\/strong><\/h2>\n\n\n\n<p>Das Projekt sollte in den Jahren 2017\u20132026 anlaufen und neben der laufenden Forstwirtschaft noch zus\u00e4tzliche Aktivit\u00e4ten beinhalten. Zu diesen zus\u00e4tzlichen Aktivit\u00e4ten geh\u00f6ren die Raumgewinnung in ausgew\u00e4hlten Gebieten durch Unterpflanzung und Unterwuchs, die Verwendung zus\u00e4tzlicher Setzlinge sowie die Wiederaufforstung durch nat\u00fcrliche Aussaat. Die \u00fcbrigen zus\u00e4tzlichen Aktivit\u00e4ten dienten der Abscheidung zus\u00e4tzlicher Mengen an organischem Kohlenstoff in ausgew\u00e4hlten Forstgebieten oder der schrittweisen Speicherung des kumulierten Kohlenstoffs im Rohholz, das in Holzlagern zwecks Energiegewinnung gelagert wird.<\/p>\n\n\n\n<p>Urspr\u00fcnglich sollte mit dem Projekt in staatlich bewirtschafteten W\u00e4ldern ein Netzwerk solcher Holzlager geschaffen werden, um gro\u00dfe Rohholzmengen zu lagern, die nach klimawandelbedingt immer h\u00e4ufiger auftretenden Wetterextremereignissen wie Starkwinden oder Wirbelst\u00fcrmen zur\u00fcckbleiben. Die ORKB konstatierte jedoch, dass kein einziges Holzlager nach einem Wirbelsturm eingerichtet wurde und dass die Idee infolge ge\u00e4nderter Vorschriften f\u00fcr den Holzumschlag aufgegeben wurde.<\/p>\n\n\n\n<p>Es wurde auch angenommen, dass die versuchsweise Markteinf\u00fchrung eines nationalen Systems f\u00fcr den Handel mit inl\u00e4ndischen CO<sub>2<\/sub>-Emissionszertifikaten als Ergebnis der zus\u00e4tzlichen forstwirtschaftlichen Aktivit\u00e4ten es Stellen, die Teil des Emissionshandelssystems (EHS) der Europ\u00e4ischen Union (EU) sind, erm\u00f6glichen k\u00f6nnte, in den Jahren 2017\u20132020 Einheiten der abgeschiedenen Emissionen zu erwerben, um die Emissionsverringerungsziele der EU-Klimaregelungen zu erreichen. Die Idee stie\u00df jedoch weder bei den politischen Entscheidungstr\u00e4gerinnen und -tr\u00e4gern der EU noch bei den betreffenden Stellen auf Interesse und wurde daher wieder fallen gelassen. Auch wurde nie eine Rechtsgrundlage f\u00fcr diese Alternative zum EHS der EU erarbeitet.<\/p>\n\n\n\n<p>Die Verordnung der Staatsforste \u00fcber die <em>Forest Carbon Farms<\/em> wurde ge\u00e4ndert und der Begriff \u201ezus\u00e4tzliche Aktivit\u00e4ten\u201c neu definiert. Diese zus\u00e4tzlichen Aktivit\u00e4ten wurden als forstwirtschaftliche Aktivit\u00e4ten beschrieben, die sich mit den an den jeweiligen Standorten \u00fcblichen Verfahren \u00fcberschneiden, sowie als Umst\u00e4nde oder Aktivit\u00e4ten, die nicht im verbindlichen Forstwirtschaftsplan erfasst sind, aber darauf abzielen, in der prognostizierten Umsetzungsphase zus\u00e4tzliche CO<sub>2<\/sub>-Mengen abzutrennen.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus wurden die Zwecke der zus\u00e4tzlichen Aktivit\u00e4ten im Rahmen des Projekts <em>Forest Carbon Farms <\/em>dahingehend ge\u00e4ndert, dass zus\u00e4tzliche Mengen Biomasse f\u00fcr den k\u00fcnftigen Verkauf sowie die Versorgung erworben werden konnten. Auf diese Weise sollte zus\u00e4tzlicher Kohlenstoff gespeichert und der Aussto\u00df von Treibhausgasen, unter anderem Kohlendioxid, verringert werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ORKB-Pr\u00fcfung und -Erkenntnisse bez\u00fcglich des Projekts<\/strong><strong><em> Forest Carbon Farms<\/em><\/strong><\/h2>\n\n\n\n<p>Die ORKB kam zu dem Schluss, dass die beiden oben genannten Projektziele widerspr\u00fcchlich sind. Die Annahme, dass die Biomasse, einschlie\u00dflich der zur CO<sub>2<\/sub>-Absorption gepflanzten B\u00e4ume, sp\u00e4ter entfernt werden soll, bedeutet, dass eine Verringerung der CO<sub>2<\/sub>-Absorption zu erwarten ist, wodurch die Aktivit\u00e4ten zur Speicherung zus\u00e4tzlicher Mengen an organischem Kohlenstoff in dieser Biomasse m\u00f6glicherweise r\u00fcckg\u00e4ngig gemacht werden.<\/p>\n\n\n\n<p>Au\u00dferdem w\u00e4re der Nutzen der im Rahmen dieses Projekts gepflanzten B\u00e4ume geringer als jener der B\u00e4ume, die im Rahmen der normalen Forstwirtschaft gepflanzt werden. Vermutlich w\u00e4re das Holz nicht f\u00fcr die Herstellung von M\u00f6beln oder anderen Holzprodukten bestimmt, sondern w\u00fcrde als Brennstoff zur Energiegewinnung verwendet werden. Dies w\u00fcrde rasch zu einem erheblichen Anstieg der CO<sub>2<\/sub>-Emissionen, die \u00fcber viele Jahre hinweg in diesen B\u00e4umen gespeichert wurden, f\u00fchren.<\/p>\n\n\n\n<p>Den Pr\u00fcfungsergebnissen der ORKB zufolge hatten die Resultate des Projekts <em>Forest Carbon Farms<\/em> und seiner Fortsetzung, des Entwicklungsprojekts <em>Carbon Forest<\/em>, keinen wirklichen Einfluss auf die st\u00e4rkere Verringerung der CO<sub>2<\/sub>-Emissionen. Im Durchschnitt lagen die j\u00e4hrlichen CO<sub>2<\/sub>-Emissionen landesweit bei etwa 325,6&nbsp;Millionen Tonnen, w\u00e4hrend sich das grundlegende Projektergebnis auf nur 1,006&nbsp;Millionen Tonnen CO<sub>2<\/sub> belief. Bei sp\u00e4teren Neubewertungen der Prognosen, im April&nbsp;2023, war es auf 0,929&nbsp;Millionen Tonnen CO<sub>2<\/sub> gesunken.<\/p>\n\n\n\n<p>Das prognostizierte Ergebnis des auf eine 30-j\u00e4hrige Laufzeit (2017\u20132046) ausgelegten Projekts war ein Mehrwert an abgeschiedenem CO<sub>2<\/sub>. Der Wert wurde vom Forests Research Institute mithilfe einer speziellen Software (kanadisches Modell CBM-CFS3) berechnet. F\u00fcr die Berechnungen wurden Datenbanken verwendet, die folgende Angaben enthielten: Pflanzenarten, Alter, Fl\u00e4che der Forstgebiete, Art der Bewirtschaftung, bewirtschaftete Fl\u00e4che und Bestandsentwicklung.<\/p>\n\n\n\n<p>Die Anwendung der aktuellen Forschungsergebnisse auf den ermittelten Algorithmus f\u00fchrte zu einem schlechteren Projektergebnis als geplant. Die mit der genannten Methode berechnete Menge an zus\u00e4tzlich abgeschiedenem CO<sub>2<\/sub> h\u00e4tte keinen nennenswerten Einfluss auf die landesweite Verringerung der CO<sub>2<\/sub>-Emissionen. Die angenommene CO<sub>2<\/sub>-Kompensation von etwa 0,031\u00a0Millionen Tonnen j\u00e4hrlich war mehr als tausendmal niedriger als die Emissionen eines einzigen Kraftwerks, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Be%25C5%2582chat%25C3%25B3w_Power_Station\">Be\u0142chat\u00f3w<\/a> (38\u00a0Millionen Tonnen), und weniger als 0,1\u00a0Prozent der gesamten CO<sub>2<\/sub>-Emissionen Polens, die im Jahr\u00a02021 bei 331,6\u00a0Millionen Tonnen CO<sub>2<\/sub> lagen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Zunahme der Holzernte in den von den polnischen Staatsforsten verwalteten W\u00e4ldern<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"697\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM-1024x697.png\" alt=\"\" class=\"wp-image-34270\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM-1024x697.png 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM-300x204.png 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM-768x523.png 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM-1320x898.png 1320w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Screenshot-2025-04-07-at-3.23.33-PM.png 1452w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Nach den statistischen Jahrb\u00fcchern 2017\u20132023, Statistikamt Polen<\/figcaption><\/figure>\n\n\n\n<p>Gleichzeitig erh\u00f6hten die Staatsforste in jedem Jahr der Projektdurchf\u00fchrung die Holzernte. Die ORKB kam zu dem Schluss, dass der eigentliche Zweck des Projekts lediglich darin bestand, das Image der Staatsforste durch \u201eGreenwashing\u201c der Abholzung aufzupolieren. Auf diese Weise sollte der Eindruck erweckt werden, dass der Betrieb den Klimawandel eind\u00e4mmt, und die Aufmerksamkeit der \u00d6ffentlichkeit von der r\u00e4uberischen Entwaldung abgelenkt werden.<\/p>\n\n\n\n<p>Die ORKB hielt fest, dass effizientere Ma\u00dfnahmen zur Verringerung der CO<sub>2<\/sub>-Emissionen die Ausweitung der Waldfl\u00e4chen und die Begrenzung der Holzernte w\u00e4ren \u2013 insbesondere zur Gewinnung von Biomasse \u2013, wodurch die CO<sub>2<\/sub>-Emissionen unterm Strich weiter verringert werden k\u00f6nnten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ORKB-Pr\u00fcfung stellt M\u00e4ngel aufgrund von unzuverl\u00e4ssiger Planung und Kontrolle fest<\/strong><\/h2>\n\n\n\n<p>Abgesehen vom \u201eGreenwashing\u201c des Image der Staatsforste und der beteiligten Einrichtungen, die einige der Projektaktivit\u00e4ten kofinanzierten, trug das Projekt nur geringf\u00fcgig zu echten L\u00f6sungen f\u00fcr die \u00fcberh\u00f6hten CO<sub>2<\/sub>-Emissionen Polens bei.<\/p>\n\n\n\n<p>Die ORKB-Pr\u00fcfung ergab, dass die Ausgaben f\u00fcr das Forschungsprojekt <em>Forests Carbon Farms<\/em> in H\u00f6he von PLN&nbsp;65,5 Millionen (ca. EUR&nbsp;15 Millionen) im Zeitraum 2017\u20132023 ineffizient get\u00e4tigt wurden. Das Hauptziel der Projektdurchf\u00fchrung \u2013 die Erh\u00f6hung der Kohlendioxidabsorption durch W\u00e4lder \u2013 hatte nur unwesentliche Auswirkungen auf die Erh\u00f6hung der CO<sub>2<\/sub>-Emissionsverringerungsrate.<\/p>\n\n\n\n<p>Trotz der Ineffizienz des ersten Projekts beschloss der Leiter der Staatsforste im Jahr&nbsp;2022 dessen Fortsetzung in Form eines zweiten Projekts, <em>Carbon Forests<\/em>, mit geplanten Ausgaben in H\u00f6he von PLN&nbsp;398,8 Millionen (ca. EUR&nbsp;93 Millionen), die mit Eigenmitteln der Staatsforste gedeckt werden sollen.<\/p>\n\n\n\n<p>Die durchgef\u00fchrten Aktivit\u00e4ten sollten einerseits dazu f\u00fchren, dass zus\u00e4tzliche Mengen an organischem Kohlenstoff in den W\u00e4ldern zur CO<sub>2<\/sub>-Absorption gespeichert werden. Andererseits sollten diese Speicherw\u00e4lder genutzt werden, um zus\u00e4tzliche Biomasse zu gewinnen und zu verkaufen, die bei einer energetischen Nutzung zum Aussto\u00df des zuvor absorbierten CO<sub>2<\/sub> f\u00fchren w\u00fcrde.<\/p>\n\n\n\n<p>Das Projekt <em>Forest Carbon Farms<\/em> wurde nicht ordnungsgem\u00e4\u00df vorbereitet: Die zu erwartenden Kosten f\u00fcr seine Umsetzung wurden nicht angegeben. Im Jahr&nbsp;2023, zum Zeitpunkt der ORKB-Pr\u00fcfung, wurden die Ausgaben auf PLN&nbsp;78,6 Millionen gesch\u00e4tzt.<\/p>\n\n\n\n<p>Der fehlende Finanzplan des Projekts war der effektiven Mittelverwendung nicht f\u00f6rderlich. Im Rahmen des Projekts konnten die Ausgaben nur begrenzt wirksam kontrolliert und auf das Hauptziel des Projekts fokussiert werden: die Erh\u00f6hung der vom Wald\u00f6kosystem absorbierten CO<sub>2<\/sub>-Menge.<\/p>\n\n\n\n<p>Der Umweltminister \u00fcbte keine zuverl\u00e4ssige Kontrolle \u00fcber die Planung und Durchf\u00fchrung des Projekts <em>Forest Carbon Farms<\/em> aus. Er sorgte nicht daf\u00fcr, dass der Generaldirektor der Staatsforste ausreichend Einfluss auf die Vorbereitung und Durchf\u00fchrung des Projekts nehmen konnte. Gem\u00e4\u00df der Strategie f\u00fcr eine verantwortungsvolle Entwicklung in Polen war das Umweltministerium f\u00fcr die Vorbereitung sowie Durchf\u00fchrung des Projekts und der Minister f\u00fcr die Kontrolle der Staatsforste sowie der Forstwirtschaft in den das Projekt durchf\u00fchrenden Gebieten zust\u00e4ndig.<\/p>\n\n\n\n<p>Der Minister bem\u00fchte sich nicht darum, vom Generaldirektor der Staatsforste einen zuverl\u00e4ssigen Kostenvoranschlag f\u00fcr das Projekt zu erhalten. Dadurch war er nur begrenzt imstande, die f\u00fcr die Durchf\u00fchrung des Projekts vorgesehenen Ausgaben zu kontrollieren.<\/p>\n\n\n\n<p>Die ministerielle Aufsicht \u00fcber die Staatsforste war w\u00e4hrend der Projektdurchf\u00fchrung unzureichend und beschr\u00e4nkte sich auf die Annahme periodischer Berichte. Die Berichte enthielten keine ausreichend gr\u00fcndliche Analyse der Daten, die sich laut ORKB-Pr\u00fcfung als unzuverl\u00e4ssig herausstellten.<\/p>\n\n\n\n<p>In fast einem Drittel aller Forstgebiete, die in das Carbon-Farms-Projekt einbezogen waren, wurden Aktivit\u00e4ten durchgef\u00fchrt, die keinen Beitrag zur Erreichung des Hauptziels des Projekts leisteten, n\u00e4mlich der Erh\u00f6hung der vom Wald\u00f6kosystem absorbierten CO<sub>2<\/sub>-Menge. Die prognostizierte zus\u00e4tzliche CO<sub>2<\/sub>-Absorptionsmenge \u00fcber 30&nbsp;Jahre hinweg entsprach entweder einem negativen Wert oder null. Dies bedeutet, dass die Projektumsetzung in diesen Gebieten im Vergleich zu regul\u00e4ren Aktivit\u00e4ten ohne Projektumsetzung (bei denen die Verringerung h\u00f6her ausfallen w\u00fcrde) zu einer geringeren CO<sub>2<\/sub>-Absorption f\u00fchrte oder dass keine zus\u00e4tzliche Kohlenstoffdioxidabsorption erzielt werden konnte.<\/p>\n\n\n\n<p>Die Angaben in den periodischen Fortschrittsberichten f\u00fcr den Zeitraum 2019\u20132023, die der Generaldirektor der Staatsforste dem Minister f\u00fcr Klima und Umwelt vorlegte, entsprachen nicht der tats\u00e4chlichen Situation in Bezug auf die H\u00f6he der angefallenen Kosten, den Umsetzungsgrad der einzelnen Aktivit\u00e4ten sowie die erzielten Ergebnisse. Die Staatsforste \u00fcberwachten den Projektfortschritt unzuverl\u00e4ssig und einige Berichtsdokumente wurden erst w\u00e4hrend der ORKB-Pr\u00fcfung erstellt, darunter auch die internen Vorschriften der Staatsforste zu den Annahmen und Durchf\u00fchrungsbestimmungen.<\/p>\n\n\n\n<p>Die an dem Projekt beteiligten Forstgebiete erf\u00fcllten ihre Aufgaben im Einklang mit den getroffenen Annahmen und gingen sparsam mit den zugewiesenen Mitteln um. Bis Ende&nbsp;2022 f\u00fchrten sie Aktivit\u00e4ten auf etwa 76&nbsp;% der Fl\u00e4che, die im Zeitraum 2017\u20132024 vom Projekt abgedeckt werden sollte, durch.<\/p>\n\n\n\n<p>Zun\u00e4chst f\u00fchrten die Forstgebiete ihre Aktivit\u00e4ten nur auf Grundlage von Absprachen mit dem Generaldirektor der Staatsforste durch, ohne Informationen \u00fcber ihre voraussichtlichen Auswirkungen auf die Umwelt, auch nicht \u00fcber die CO<sub>2<\/sub>-Absorptionsmenge, da die Anwendung, welche die Ausarbeitung der einzelnen Aufgaben im Rahmen des Projekts erm\u00f6glicht, den Forstgebieten erst im September&nbsp;2018 zur Verf\u00fcgung gestellt wurde.<\/p>\n\n\n\n<p>In \u00fcber der H\u00e4lfte der Forstgebiete gab es F\u00e4lle, in denen die j\u00e4hrlichen Fortschrittsberichte versp\u00e4tet eingereicht wurden, sowie F\u00e4lle, in denen Daten unzuverl\u00e4ssig angegeben wurden (zum Beispiel zu niedrige Angaben zu den entstandenen Kosten).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fazit<\/strong><\/h2>\n\n\n\n<p>In Anbetracht der Gesamtverantwortung f\u00fcr die Projektkontrolle, die dem Klima- und Umweltminister in Bezug auf die Vorbereitung und Durchf\u00fchrung des Projekts \u00fcbertragen wurde, sowie der Zust\u00e4ndigkeit des Generaldirektors der Staatsforste f\u00fcr die Projektdurchf\u00fchrung empfahl die ORKB, die Durchf\u00fchrung des Projekts <em>Carbon Forests<\/em> auszusetzen, bis das Pilotforschungsprojekt <em>Carbon Forest Farms<\/em> abgeschlossen ist und die erzielten Ergebnisse zusammengetragen wurden. Die ORKB empfahl dem Klima- und Umweltminister au\u00dferdem, eine gr\u00fcndliche Analyse der Begr\u00fcndung f\u00fcr das Projekt <em>Carbon Forests<\/em> vorzunehmen und dabei die laut Prognosen schwachen Ergebnisse des Projekts <em>Carbon Forest Farms <\/em>zu ber\u00fccksichtigen.<\/p>\n\n\n\n<p><em>F\u00fcr weitere Informationen besuchen Sie bitte: <a href=\"https:\/\/www.nik.gov.pl\/aktualnosci\/lesne-gospodarstwa-weglowe.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nik.gov.pl\/aktualnosci\/lesne-gospodarstwa-weglowe.html<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Oberste Rechnungshof der Republik Polen pr\u00fcfte die Umsetzung eines strategischen Pilotprojekts, der Forest Carbon Farms (dt. etwa \u201eWaldkohlenstoffbetriebe\u201c), um dessen Leistung zu \u00fcberpr\u00fcfen und festzustellen, ob die Mittel w\u00e4hrend der Umsetzung durch die Generaldirektion Staatsforste effizient eingesetzt wurden. Bei der Pr\u00fcfung wurde auch untersucht, ob die besten Ergebnisse erzielt werden konnten und ob die Forstgebiete ihre Aktivit\u00e4ten im Rahmen des Projekts korrekt und zuverl\u00e4ssig geplant sowie durchgef\u00fchrt haben.\u00a0<\/p>\n","protected":false},"author":321,"featured_media":34239,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[4042],"content-tags":[3659,3605,2436,2312,2175],"country":[3218],"region":[2597],"section":[2603],"coauthors":[4023],"class_list":["post-34263","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q1-2025-de","content-tags-audit-methodology-de","content-tags-climatechange-de","content-tags-prufungsauswirkungen","content-tags-umweltauditierung","content-tags-wirtschaftlichkeitsprufung","country-poland-de","region-eurosai-de","section-fachartikel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Der Oberste Rechnungshof der Republik Polen pr\u00fcfte die Umsetzung eines strategischen Pilotprojekts, der Forest Carbon Farms (dt. etwa \u201eWaldkohlenstoffbetriebe\u201c), um dessen Leistung zu \u00fcberpr\u00fcfen und festzustellen, ob die Mittel w\u00e4hrend der Umsetzung durch die Generaldirektion Staatsforste effizient eingesetzt wurden. Bei der Pr\u00fcfung wurde auch untersucht, ob die besten Ergebnisse erzielt werden konnten und ob die Forstgebiete ihre Aktivit\u00e4ten im Rahmen des Projekts korrekt und zuverl\u00e4ssig geplant sowie durchgef\u00fchrt haben.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T20:29:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Iwona Zubrzycka-Wasil\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/\",\"url\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/\",\"name\":\"Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png\",\"datePublished\":\"2025-04-16T20:26:42+00:00\",\"dateModified\":\"2025-04-16T20:29:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage\",\"url\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png\",\"contentUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png\",\"width\":1326,\"height\":880,\"caption\":\"Wiederaufforstung eines Kiefernwaldes. Quelle: Adobe Stock Images, Sergey + Marina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Greenwashing der staatlichen Holzernte in Polen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/","og_locale":"de_DE","og_type":"article","og_title":"Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal","og_description":"Der Oberste Rechnungshof der Republik Polen pr\u00fcfte die Umsetzung eines strategischen Pilotprojekts, der Forest Carbon Farms (dt. etwa \u201eWaldkohlenstoffbetriebe\u201c), um dessen Leistung zu \u00fcberpr\u00fcfen und festzustellen, ob die Mittel w\u00e4hrend der Umsetzung durch die Generaldirektion Staatsforste effizient eingesetzt wurden. Bei der Pr\u00fcfung wurde auch untersucht, ob die besten Ergebnisse erzielt werden konnten und ob die Forstgebiete ihre Aktivit\u00e4ten im Rahmen des Projekts korrekt und zuverl\u00e4ssig geplant sowie durchgef\u00fchrt haben.\u00a0","og_url":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/","og_site_name":"INTOSAI Journal","article_modified_time":"2025-04-16T20:29:11+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"9 minutes","Written by":"Iwona Zubrzycka-Wasil"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/","url":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/","name":"Greenwashing der staatlichen Holzernte in Polen - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage"},"image":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png","datePublished":"2025-04-16T20:26:42+00:00","dateModified":"2025-04-16T20:29:11+00:00","breadcrumb":{"@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#primaryimage","url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png","contentUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2025\/04\/Cover-Poland-Q1-2025.png","width":1326,"height":880,"caption":"Wiederaufforstung eines Kiefernwaldes. Quelle: Adobe Stock Images, Sergey + Marina"},{"@type":"BreadcrumbList","@id":"https:\/\/intosaijournal.org\/de\/journal-entry\/greenwashing-der-staatlichen-holzernte-in-polen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/de\/"},{"@type":"ListItem","position":2,"name":"Greenwashing der staatlichen Holzernte in Polen"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/34263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/users\/321"}],"version-history":[{"count":3,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/34263\/revisions"}],"predecessor-version":[{"id":34278,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/34263\/revisions\/34278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media\/34239"}],"wp:attachment":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media?parent=34263"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-categories?post=34263"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/content-tags?post=34263"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/country?post=34263"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/region?post=34263"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/section?post=34263"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/coauthors?post=34263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}