{"id":27646,"date":"2024-06-02T16:32:23","date_gmt":"2024-06-02T20:32:23","guid":{"rendered":"https:\/\/intosaijournal.org\/?post_type=journal-entry&#038;p=27646"},"modified":"2024-06-02T19:02:41","modified_gmt":"2024-06-02T23:02:41","slug":"7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand","status":"publish","type":"journal-entry","link":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/","title":{"rendered":"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand"},"content":{"rendered":"\n<p>Auteur&nbsp;:&nbsp;Dr Sutthi Suntharanurak<\/p>\n\n\n\n<p><strong><em>Das 7.&nbsp;Forum der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen<\/em><\/strong>, das am 16. und 17.&nbsp;Oktober 2023 in Bangkok stattfand, wurde mit einer Auftaktzeremonie, bei der eine Reihe hochrangiger Rednerinnen und Redner \u00fcber die globale Bedeutung und die partnerschaftliche Absicht der Veranstaltung sprachen, feierlich er\u00f6ffnet.<strong><em>General Chanathap Indamra<\/em><\/strong>, Leiter der ORKB Thailand und Vorsitzender der ASOSAI, hie\u00df die Teilnehmenden herzlich willkommen und legte den Grundstein f\u00fcr eine kameradschaftliche Atmosph\u00e4re und ein gemeinsames Ziel f\u00fcr die Veranstaltung. <strong>Herr Jean Yves Bertucci,<\/strong> Leiter der Kammer des franz\u00f6sischen Rechnungshofs, teilte seine Einblicke und bereicherte den Austausch mit Perspektiven aus dem Forum der ORKB mit Rechtsprechungsbefugnissen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-1024x682.jpeg\" alt=\"\" class=\"wp-image-26544\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-1024x682.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-300x200.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-768x512.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-660x440.jpeg 660w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-193x128.jpeg 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-310x206.jpeg 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large-467x310.jpeg 467w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1224-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong><em>General Chanathap Indamra<\/em><\/strong><em>, Leiter der ORKB Thailand und Vorsitzender der ASOSAI.<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-1024x682.jpeg\" alt=\"\" class=\"wp-image-26549\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-1024x682.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-300x200.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-768x512.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-660x440.jpeg 660w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-193x128.jpeg 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-310x206.jpeg 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large-467x310.jpeg 467w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1235-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong><em>Herr Jean Yves Bertucci<\/em><\/strong><em>, Leiter der Kammer des franz\u00f6sischen Rechnungshofs.<\/em><\/figcaption><\/figure>\n\n\n\n<p><strong><em>Herr Carlos Riofrio Gonzalez<\/em><\/strong>, Leiter der ORKB Ecuador, trug mit einer Videopr\u00e4sentation zur Perspektivenvielfalt bei und sorgte daf\u00fcr, dass die weltweite Gemeinschaft der ORKB trotz geografischer Entfernung gut vertreten war. An der Veranstaltung nahmen auch <strong><em>Herr Bruno Dantas<\/em><\/strong>, INTOSAI-Vorsitzender und Leiter der ORKB Brasilien, sowie <strong><em>Frau Zineb El Adaoui<\/em><\/strong>, Leiterin der ORKB Marokko, teil. Zusammen stellten sie <strong><em>das JuriSAI-Projekt<\/em><\/strong> vor, ein bahnbrechendes Projekt, mit dem Ziel, die Zusammenarbeit und den Wissensaustausch unter ORKB mit Rechtsprechungsbefugnissen auf der ganzen Welt zu f\u00f6rdern.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-1024x682.jpeg\" alt=\"\" class=\"wp-image-26554\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-1024x682.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-300x200.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-768x512.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-660x440.jpeg 660w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-193x128.jpeg 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-310x206.jpeg 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large-467x310.jpeg 467w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC1333-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Das 7.&nbsp;Forum der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen wurde von der ORKB Thailand am 16. und 17.&nbsp;Oktober 2023 in Bangkok ausgerichtet.<\/em><\/figcaption><\/figure>\n\n\n\n<p><strong><em>Professorin Dr.<sup>in<\/sup> Orapin Phonsuwan Sabyeroop<\/em><\/strong> sprach in ihrem Impulsvortrag anl\u00e4sslich des Forums \u00fcber die transformative Reise Thailands im Bereich Steuer- und Finanzdisziplin und pr\u00e4sentierte die zentralen Meilensteine, die das Pr\u00fcfsystem der Nation pr\u00e4gten. Ihr Beitrag war ein Beleg f\u00fcr ihren starken Einfluss in dem Bereich. In ihrem Vortrag <strong><em>f\u00fchrte<\/em><\/strong> sie durch die historische Entwicklung der staatlichen Finanzkontrolle in Thailand und betonte ihre eigenen wissenschaftlichen Beitr\u00e4ge, die als Katalysatoren f\u00fcr wesentliche Reformen und die anschlie\u00dfende Ausarbeitung eines globalen Normen entsprechenden Pr\u00fcfungsrahmenwerks fungierten. Sie zeigte entscheidende Entwicklungen genau auf, zum Beispiel die Verlagerung hin zu einem autonomeren Pr\u00fcfsystem, die Erstellung eines Pr\u00fcfungsgesetzes sowie die Gr\u00fcndung des Komitees zu Haushalts- und Finanzdisziplin. Diese Schritte dienten der St\u00e4rkung von Effizienz und Transparenz in der Verwaltung des \u00f6ffentlichen Sektors.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC2063-Large-1024x768.jpeg\" alt=\"\" class=\"wp-image-26559\" style=\"aspect-ratio:1.3333333333333333;width:1029px;height:auto\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC2063-Large-1024x768.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC2063-Large-300x225.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC2063-Large-768x576.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/DSC2063-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Professorin Dr.<sup>in<\/sup> Orapin Phonsuwan Sabyeroop, Kommissarin der staatlichen Pr\u00fcfkommission Thailand, Hauptrednerin des Treffens.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Als Kommissarin der staatlichen Pr\u00fcfkommission sah Professorin Dr.<sup>in<\/sup> Orapin anhaltenden Bedarf f\u00fcr weitere Reformen zur Begr\u00fcndung gerichtlicher Zust\u00e4ndigkeiten in Thailand. Sie betonte, wie entscheidend es ist, dass sich das Pr\u00fcfungsverfahren durch Unabh\u00e4ngigkeit und Unparteilichkeit auszeichnet. Diese Grunds\u00e4tze sind unerl\u00e4sslich, um die Pr\u00fcfungsmethoden Thailands in Einklang mit international anerkannten Normen zu bringen. In ihrem Vortrag ging sie nicht nur auf die bisherigen Erfolge ein, sondern gab auch einen Ausblick auf die k\u00fcnftige Ausrichtung zur Verbesserung der Integrit\u00e4t und Wirksamkeit der thail\u00e4ndischen Steuer- und Finanzverwaltung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-1024x682.png\" alt=\"\" class=\"wp-image-26564\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-1024x682.png 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-300x200.png 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-768x512.png 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-660x440.png 660w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-1320x880.png 1320w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-193x128.png 193w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-310x206.png 310w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image-467x310.png 467w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/image.png 1379w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong><em>Herr Bruno Dantas<\/em><\/strong><em>, INTOSAI-Vorsitzender und Leiter der ORKB Brasilien, und <\/em><strong><em>Frau Zineb El Adaoui<\/em><\/strong><em>, Leiterin der ORKB Marokko. Gemeinsam stellten sie das JuriSAI-Projekt vor.<\/em><\/figcaption><\/figure>\n\n\n\n<p>In seiner anl\u00e4sslich des im Oktober&nbsp;2023 abgehaltenen Forums in Bangkok gehaltenen <strong>Pr\u00e4sentation<\/strong> hob <strong>Herr Miller<\/strong> von der ORKB Frankreich Fortschritte in drei Schl\u00fcsselbereichen hervor:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong><em>Interessenvertretung und Sichtbarkeit:<\/em><\/strong> Die weltweite Weitergabe des Positionspapiers an wichtige Steuerungsorganisationen (IWF, Weltbank, EU usw.) im Juni&nbsp;2023 wurde enthusiastisch aufgenommen und spiegelte eine positive R\u00fcckmeldung zu Initiativen, die auf die bessere Anerkennung und ein besseres Verst\u00e4ndnis f\u00fcr die Bedeutung und die Nutzen von ORKB mit Rechtsprechungsbefugnissen abzielen, wider.<\/li>\n\n\n\n<li><strong><em>Institutionalisierung:<\/em><\/strong> Es gab aktive Diskussionen zur formelleren Eingliederung des Forums in die INTOSAI-Gemeinschaft. Dazu z\u00e4hlten Schritte zur Einrichtung des Forums als eigene Arbeitsgruppe. Es besteht weiterhin unersch\u00fctterlicher Einsatz f\u00fcr die Erreichung dieses Ziels.<\/li>\n\n\n\n<li><strong><em>Publikationen:<\/em><\/strong> Die Zusammenarbeit mit der INTOSAI-Zeitschrift zielt darauf ab, ORKB mit Rechtsprechungsbefugnissen im Jahr&nbsp;2024 herauszustreichen, um bew\u00e4hrte Verfahren, Erkenntnisse und Fortschritte in der ORKB-Gemeinschaft weiter zu verbreiten. Dadurch wird der Einsatz des Forums f\u00fcr Wissensaustausch sowie die Unterst\u00fctzung von ORKB mit Rechtsprechungsbefugnissen in den Vordergrund gestellt.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Podium&nbsp;1 \u2013 Die Rolle von Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen im Kampf gegen Betrug und Korruption<\/strong><\/strong><\/h2>\n\n\n\n<p>In seiner am 16.&nbsp;Oktober 2023 in Bangkok gehaltenen Pr\u00e4sentation betonte <strong><em>Herr Ramadhani<\/em><\/strong> als Vertreter der ORKB Indonesien die zentrale Rolle der Organisation im Kampf gegen Betrug und Korruption in Indonesien. Zu den wichtigsten Punkten z\u00e4hlten:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong><em>Rechtsrahmen und Mandat:<\/em><\/strong> Die ORKB Indonesien bezieht ihre Handlungsf\u00e4higkeit aus einem umfassenden Rechtsrahmen, der ihr die Zust\u00e4ndigkeit \u00fcbertr\u00e4gt, die Verwaltung und Rechenschaftspflicht im Bereich der Staatsfinanzen zu pr\u00fcfen. Dazu geh\u00f6rt ebenfalls die Befugnis, finanzielles Fehlverhalten und Korruption zu untersuchen und zu melden.<\/li>\n\n\n\n<li><strong>Pr\u00fcfungsumfang und -arten:<\/strong> Herr Ramadhani erl\u00e4uterte das breite Spektrum der von der ORKB Indonesien durchgef\u00fchrten Pr\u00fcfungen, zum Beispiel Pr\u00fcfungen der Rechnungsf\u00fchrung, Wirtschaftlichkeitspr\u00fcfungen und Ermittlungspr\u00fcfungen, die speziell auf die Aufdeckung von Betrug und Korruption ausgerichtet sind, und stellte den gr\u00fcndlichen Ansatz der Institution zur Gew\u00e4hrleistung finanzieller Integrit\u00e4t vor.<\/li>\n\n\n\n<li><strong>Durchsetzung und Zusammenarbeit:<\/strong> In der Pr\u00e4sentation wurde die Bedeutung der Zusammenarbeit mit Strafverfolgungsbeh\u00f6rden hervorgehoben. Dabei wurde beschrieben, wie die ORKB Indonesien bei Pr\u00fcfungen gewonnene Erkenntnisse \u00fcber kriminelle Aktivit\u00e4ten den entsprechenden Strafverfolgungsbeh\u00f6rden meldet und dass sie eine Rolle bei der Einsch\u00e4tzung der finanziellen Verluste auf staatlicher sowie regionaler Ebene spielt und daher aktiv an Rechtsverfahren zu finanziellen Unregelm\u00e4\u00dfigkeiten beteiligt ist.<\/li>\n<\/ol>\n\n\n\n<p>Diese Punkte zeigen den Beitrag der ORKB Indonesien zur Verbesserung der finanziellen Transparenz, Rechenschaftspflicht und Integrit\u00e4t im Governance-Rahmenwerk Indonesiens auf.<\/p>\n\n\n\n<p>In ihrer Pr\u00e4sentation gew\u00e4hrte <strong><em>Frau Dujols <\/em><\/strong>Einblicke in die Zusammenarbeit zwischen <strong><em>dem franz\u00f6sischen Rechnungshof und den Justizbeh\u00f6rden<\/em><\/strong> und legte dabei besonderes Augenmerk auf einen konkreten Fall, in dem es in der \u201eO\u201c-Beh\u00f6rde, einer \u00f6ffentlichen Stelle, die Opfern von medizinischen Verletzungen Hilfe leistet, zu Missmanagement und ethischen Verst\u00f6\u00dfen kam. Zu den wichtigsten Punkten z\u00e4hlten die Ermittlung schwerwiegender Probleme im Bereich Management und Ethik sowie die Zusammenarbeit von Pr\u00fcferinnen und Pr\u00fcfern der Rechnungsf\u00fchrung mit Staatsanw\u00e4ltinnen und -anw\u00e4lten, die zu bedeutenden Rechts- und Verwaltungsma\u00dfnahmen gegen die Leitung der Beh\u00f6rde sowie zu den daraus resultierenden R\u00fcckforderungen und Reformen f\u00fchrte. Dieser Fall diente als Paradebeispiel f\u00fcr eine wirksame Partnerschaft zwischen Rechnungskontrollbeh\u00f6rden und dem Justizsystem im Kampf gegen Korruption und Missmanagement.<\/p>\n\n\n\n<p>In seinen Ausf\u00fchrungen anl\u00e4sslich des Forums f\u00fcr ORKB mit Rechtsprechungsbefugnissen beleuchtete <strong><em>Herr Batonon von der ORKB Benin<\/em><\/strong> die pr\u00e4ventiven und korrektiven Rollen, die ORKB im Kampf gegen Betrug und Korruption einnehmen. Er betonte den Gendarmeffekt der ORKB f\u00fcr die Vorbeugung von Fehlverhalten, ihre beratende Rolle gegen\u00fcber der \u00f6ffentlichen Verwaltung zu l\u00f6sungsorientierten Managementmethoden und die Notwendigkeit, schlechte Verwaltung zu sanktionieren. Herr Batonon trat daf\u00fcr ein, dass ORKB eine proaktive Rolle einnehmen, in der \u00f6ffentlichen Verwaltung sichtbar bleiben und eine ausschlaggebende Rolle bei der Aufrechterhaltung von Rechenschaftspflicht sowie Steuerdisziplin spielen sollten. Zudem hob er ihre zentrale Stellung bei der F\u00f6rderung guter Regierungsf\u00fchrung und der Korruptionseind\u00e4mmung hervor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Podium&nbsp;2 \u2013 Notwendigkeit der internationalen Zusammenarbeit und des Informationsaustauschs<\/strong><\/strong><\/h2>\n\n\n\n<p>In seiner Pr\u00e4sentation betonte Herr Batonon die zentrale Rolle der internationalen Zusammenarbeit und des Informationsaustauschs im Kampf gegen Betrug und Korruption. Er berichtete ausf\u00fchrlich \u00fcber die globale Dimension dieser Delikte und die dringende Notwendigkeit f\u00fcr Oberste Rechnungskontrollbeh\u00f6rden (ORKB), \u00fcber nationale Grenzen hinweg zusammenzuarbeiten. Batonon sprach sich f\u00fcr die Einrichtung von Datenbanken aus, die \u00f6ffentliche Finanzprozesse mit internationalen Auswirkungen beinhalten, und forderte einen verbesserten Erkenntnis- und Datenaustausch unter ORKB. Diese Ma\u00dfnahmen zielen darauf ab, die weltweiten Bem\u00fchungen zur Aufdeckung und Verhinderung von Korruption zu verst\u00e4rken, und betonen den Wert gemeinsamer Initiativen zur Verbesserung der Rechenschaftspflicht und der Governance im \u00f6ffentlichen Sektor.<\/p>\n\n\n\n<p><strong><em>Herr Diatta von der ORKB Senegal<\/em><\/strong> hob in seinem Vortrag die entscheidende Rolle der ORKB bei der F\u00f6rderung von Transparenz, Rechtm\u00e4\u00dfigkeit und der effizienten Verwendung \u00f6ffentlicher Gelder hervor. Gleichzeitig ging er auf die von ORKB angetroffenen Hindernisse, unter anderem die ausgekl\u00fcgelten Betrugsmethoden, und die unabdingbare Notwendigkeit einer grenz\u00fcberschreitenden Zusammenarbeit ein. Er pr\u00e4sentierte Beispiele f\u00fcr erfolgreiche internationale Zusammenarbeit und gab Empfehlungen f\u00fcr die Steigerung der Leistungsf\u00e4higkeit der ORKB in ihrem Feldzug gegen Betrug und Korruption ab. Herr Diatta betonte die Bedeutung solider Rechtsstrukturen und globaler Partnerschaften und unterstrich die Notwendigkeit gemeinsamer Bem\u00fchungen zur Intensivierung des Kampfs gegen Korruption durch gest\u00e4rkte rechtliche und operative Rahmenbedingungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Podium&nbsp;3 \u2013 Initiativen f\u00fcr Korruptionspr\u00e4vention und Bewusstseinssch\u00e4rfung der \u00d6ffentlichkeit<\/strong><\/strong><\/h2>\n\n\n\n<p>In seiner Pr\u00e4sentation hob Herr <strong><em>Orefice<\/em><\/strong> die Rolle des <strong><em>italienischen Rechnungshofs<\/em><\/strong> f\u00fcr die F\u00f6rderung der Transparenz, Rechenschaftspflicht und Gesetzeseinhaltung hervor. Er betonte, wie wichtig es sei, pr\u00e4ventive Ma\u00dfnahmen zu ergreifen, das Bewusstsein der \u00d6ffentlichkeit zu sch\u00e4rfen und Partnerschaften mit Bildungseinrichtungen einzugehen, um so demokratische Werte sowie die aktive Einbindung von B\u00fcrgerinnen und B\u00fcrgern zu f\u00f6rdern. Die Initiative \u201eEducating in Legality\u201c (dt. etwa \u201eRechtm\u00e4\u00dfigkeitsbildung\u201c) f\u00fcr die Einbindung der Jugend und die Erweiterung ihres Verst\u00e4ndnisses f\u00fcr die Rolle, die der italienische Rechnungshof f\u00fcr den Schutz \u00f6ffentlicher Gelder spielt, wurde als zentrale Ma\u00dfnahme und ganzheitliche Strategie in der Korruptionsbek\u00e4mpfung aufgef\u00fchrt.<\/p>\n\n\n\n<p><strong><em>Herr Arifa <\/em><\/strong>konzentrierte sich in seinem Vortrag auf die<strong><em> umfassenden Strategien der ORKB Brasilien<\/em><\/strong> im Kampf gegen Betrug sowie Korruption, die besonderes Augenmerk auf Pr\u00e4vention, Aufdeckung, Ermittlung und laufende \u00dcberwachung legen. Er hob hervor, wie wichtig es sei, verschiedene Stakeholder, insbesondere die Zivilgesellschaft, durch Bildungsprogramme, Zusammenarbeit und Technologienutzung, zum Beispiel durch Datenanalyse und KI, einzubinden, um die Wirksamkeit der Pr\u00fcfungen und Untersuchungen zu steigern. Zur Veranschaulichung der positiven Effekte dieser Strategien f\u00fchrte er Fallbeispiele an, zum Beispiel Kostensenkungen im Stromsektor und betr\u00e4chtliche Finanzeinsparungen durch beharrliche Pr\u00fcfungsmethoden, und betonte den zukunftsgerichteten Ansatz der ORKB Brasilien bei der Steigerung von Transparenz und Rechenschaftspflicht im \u00f6ffentlichen Sektor.<\/p>\n\n\n\n<p><strong><em><strong><em>Herr Arifa legte den Ansatz der ORKB Brasilien detaillierter dar:<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Umfassende Strategie: Ein ganzheitlicher Plan, der Pr\u00e4ventions-, Aufdeckungs-, Ermittlungs- und \u00dcberwachungsma\u00dfnahmen im Kampf gegen Korruption und Betrug beinhaltet.<\/li>\n\n\n\n<li>Stakeholdereinbindung: Die Einbindung der Zivilgesellschaft durch Aufkl\u00e4rung und Zusammenarbeit spielt eine ausschlaggebende Rolle, um f\u00fcr mehr Transparenz und Rechenschaftspflicht zu sorgen.<\/li>\n\n\n\n<li>Technologieeinsatz: Einf\u00fchrung von Datenanalyse und k\u00fcnstlicher Intelligenz (KI), um die Wirksamkeit der Pr\u00fcfungs- und Ermittlungsverfahren zu steigern.<\/li>\n\n\n\n<li>Wirkungsstarke Ergebnisse: In Fallstudien zeigen sich wirkungsstarke Ergebnisse, zum Beispiel Kostensenkungen im Energiesektor und betr\u00e4chtliche Einsparungen dank kontinuierlicher Pr\u00fcfungst\u00e4tigkeiten, was den konkreten Nutzen der Ma\u00dfnahmen der ORKB Brasilien aufzeigt.<\/li>\n<\/ol>\n\n\n\n<p><strong><em>Teil der Diskussion war auch Portugals Ansatz <\/em><\/strong>bei der Betrugs- und Korruptionspr\u00e4vention, den der Rat f\u00fcr Korruptionspr\u00e4vention (vom Englischen \u201eCouncil for the Prevention of Corruption\u201c kurz CPC) mit drei Hauptma\u00dfnahmen zusammenfasste: die Bereitstellung von Pl\u00e4nen zum Management von Korruptionsrisiken in \u00fcber 1.300&nbsp;staatlichen Institutionen, Bildungsbesuche, bei denen die Compliance beurteilt und diesbez\u00fcglich Verbesserungsvorschl\u00e4ge abgegeben wurden, und die Einf\u00fchrung von Bildungsprogrammen in Schulen zum Aufbau eines Anti-Korruptionsnetzwerks, mit denen Tausende Schulen sowie Sch\u00fclerinnen und Sch\u00fcler erreicht werden. Dar\u00fcber hinaus wurde der \u00dcbergang vom CPC zum nationalen Mechanismus gegen Korruption erw\u00e4hnt, der diese Ma\u00dfnahmen beibeh\u00e4lt und ein allgemeines Korruptionspr\u00e4ventionssystem einf\u00fchrt, das sowohl in privaten als auch \u00f6ffentlichen Sektoren Compliance-Programme vorsieht und Portugals Einsatz f\u00fcr die Korruptionsbek\u00e4mpfung mittels Bildung, Regulierung und systemischer Verbesserung fortf\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Fazit<\/strong><\/strong><\/h2>\n\n\n\n<p>Die globalen F\u00fchrungspers\u00f6nlichkeiten sowie Expertinnen und Experten, die anl\u00e4sslich des 7.&nbsp;Forums der ORKB mit Rechtsprechungsbefugnissen zusammenkamen, l\u00e4uteten das Forum geb\u00fchrend ein und betonten die gro\u00dfe Bedeutung des Treffens als Plattform f\u00fcr Dialog, Austausch und Fortschritt im Bereich der staatlichen Finanzkontrolle. Ihre Anwesenheit und Beitr\u00e4ge brachten den Einsatz der ORKB aller Kontinente f\u00fcr mehr Transparenz, Rechenschaftspflicht und bessere Regierungsf\u00fchrung durch gest\u00e4rkte rechtsprechende Pr\u00fcfungsmethoden zur Geltung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/1-Large-1024x576.jpeg\" alt=\"\" class=\"wp-image-26579\" style=\"aspect-ratio:1.7777777777777777;width:1024px;height:auto\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/1-Large-1024x576.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/1-Large-300x169.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/1-Large-768x432.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/1-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Quelle: Oberste Rechnungskontrollbeh\u00f6rde Thailand<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/intosaijournal.org\/wp-content\/uploads\/2024\/05\/2-Large-1024x576.jpeg\" alt=\"\" class=\"wp-image-26584\" srcset=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/2-Large-1024x576.jpeg 1024w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/2-Large-300x169.jpeg 300w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/2-Large-768x432.jpeg 768w, https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/05\/2-Large.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Quelle: Oberste Rechnungskontrollbeh\u00f6rde Thailand<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcber den Autor:<\/h2>\n\n\n\n<p>Dr. Sutthi Suntharanurak leitet die Abteilung f\u00fcr internationale Beziehungen der Obersten Rechnungskontrollbeh\u00f6rde des K\u00f6nigreichs Thailand. Wenden Sie sich bitte an: <a href=\"mailto:sutthisun@gmail.com\">sutthisun@gmail.com<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das 7.\u00a0Forum der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen, das am 16. und 17.\u00a0Oktober 2023 in Bangkok stattfand, wurde mit einer Auftaktzeremonie, bei der eine Reihe hochrangiger Rednerinnen und Redner \u00fcber die globale Bedeutung und die partnerschaftliche Absicht der Veranstaltung sprachen, feierlich er\u00f6ffnet.General Chanathap Indamra, Leiter der ORKB Thailand und Vorsitzender der ASOSAI, hie\u00df die Teilnehmenden herzlich willkommen und legte den Grundstein f\u00fcr eine kameradschaftliche Atmosph\u00e4re und ein gemeinsames Ziel f\u00fcr die Veranstaltung. Herr Jean Yves Bertucci, Leiter der Kammer f\u00fcr Streitsachen des franz\u00f6sischen Rechnungshofs, teilte seine Einblicke und bereicherte den Austausch mit Perspektiven aus dem Forum der ORKB mit Rechtsprechungsbefugnissen.<\/p>\n","protected":false},"author":37,"featured_media":26892,"template":"","meta":{"_acf_changed":false,"footnotes":""},"journal-categories":[3877],"content-tags":[3880,3836,2165],"country":[2928],"region":[2594],"section":[2603],"coauthors":[3317],"class_list":["post-27646","journal-entry","type-journal-entry","status-publish","has-post-thumbnail","hentry","journal-categories-q2-2024-de","content-tags-forum-of-jurisdictional-sais-de","content-tags-juristische-befugnisse","content-tags-weitergabe-von-wissen","country-thailand-de","region-asosai-de-2","section-fachartikel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal\" \/>\n<meta property=\"og:description\" content=\"Das 7.\u00a0Forum der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen, das am 16. und 17.\u00a0Oktober 2023 in Bangkok stattfand, wurde mit einer Auftaktzeremonie, bei der eine Reihe hochrangiger Rednerinnen und Redner \u00fcber die globale Bedeutung und die partnerschaftliche Absicht der Veranstaltung sprachen, feierlich er\u00f6ffnet.General Chanathap Indamra, Leiter der ORKB Thailand und Vorsitzender der ASOSAI, hie\u00df die Teilnehmenden herzlich willkommen und legte den Grundstein f\u00fcr eine kameradschaftliche Atmosph\u00e4re und ein gemeinsames Ziel f\u00fcr die Veranstaltung. Herr Jean Yves Bertucci, Leiter der Kammer f\u00fcr Streitsachen des franz\u00f6sischen Rechnungshofs, teilte seine Einblicke und bereicherte den Austausch mit Perspektiven aus dem Forum der ORKB mit Rechtsprechungsbefugnissen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/\" \/>\n<meta property=\"og:site_name\" content=\"INTOSAI Journal\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-02T23:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1326\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@intosaijournal\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Dr. Sutthi Suntharanurak\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/\",\"url\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/\",\"name\":\"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal\",\"isPartOf\":{\"@id\":\"https:\/\/intosaijournal.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png\",\"datePublished\":\"2024-06-02T20:32:23+00:00\",\"dateModified\":\"2024-06-02T23:02:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage\",\"url\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png\",\"contentUrl\":\"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png\",\"width\":1326,\"height\":880,\"caption\":\"Quelle: Flag \u2013 Adobe Stock Images, 12ee12; Logo \u2013 State Audit Office Thailand\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/intosaijournal.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/intosaijournal.org\/#website\",\"url\":\"https:\/\/intosaijournal.org\/\",\"name\":\"INTOSAI Journal\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/intosaijournal.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/intosaijournal.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/intosaijournal.org\/#organization\",\"name\":\"INTOSAI Journal\",\"url\":\"https:\/\/intosaijournal.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"contentUrl\":\"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png\",\"width\":736,\"height\":122,\"caption\":\"INTOSAI Journal\"},\"image\":{\"@id\":\"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/intosaijournal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/","og_locale":"de_DE","og_type":"article","og_title":"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal","og_description":"Das 7.\u00a0Forum der Obersten Rechnungskontrollbeh\u00f6rden (ORKB) mit Rechtsprechungsbefugnissen, das am 16. und 17.\u00a0Oktober 2023 in Bangkok stattfand, wurde mit einer Auftaktzeremonie, bei der eine Reihe hochrangiger Rednerinnen und Redner \u00fcber die globale Bedeutung und die partnerschaftliche Absicht der Veranstaltung sprachen, feierlich er\u00f6ffnet.General Chanathap Indamra, Leiter der ORKB Thailand und Vorsitzender der ASOSAI, hie\u00df die Teilnehmenden herzlich willkommen und legte den Grundstein f\u00fcr eine kameradschaftliche Atmosph\u00e4re und ein gemeinsames Ziel f\u00fcr die Veranstaltung. Herr Jean Yves Bertucci, Leiter der Kammer f\u00fcr Streitsachen des franz\u00f6sischen Rechnungshofs, teilte seine Einblicke und bereicherte den Austausch mit Perspektiven aus dem Forum der ORKB mit Rechtsprechungsbefugnissen.","og_url":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/","og_site_name":"INTOSAI Journal","article_modified_time":"2024-06-02T23:02:41+00:00","og_image":[{"width":1326,"height":880,"url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@intosaijournal","twitter_misc":{"Est. reading time":"10 minutes","Written by":"Dr. Sutthi Suntharanurak"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/","url":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/","name":"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand - INTOSAI Journal","isPartOf":{"@id":"https:\/\/intosaijournal.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage"},"image":{"@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png","datePublished":"2024-06-02T20:32:23+00:00","dateModified":"2024-06-02T23:02:41+00:00","breadcrumb":{"@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#primaryimage","url":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png","contentUrl":"https:\/\/www.intosaijournal.org\/wp-content\/uploads\/2024\/04\/SAI-Thailand-1.png","width":1326,"height":880,"caption":"Quelle: Flag \u2013 Adobe Stock Images, 12ee12; Logo \u2013 State Audit Office Thailand"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intosaijournal.org\/de\/journal-entry\/7-forum-der-orkb-mit-rechtsprechungsbefugnissen-findet-in-bangkok-statt-16-und-17-oktober-2023-bangkok-oberste-rechnungskontrollbehoerde-thailand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/intosaijournal.org\/de\/"},{"@type":"ListItem","position":2,"name":"7.\u00a0Forum der ORKB mit Rechtsprechungsbefugnissen findet in Bangkok statt, 16. und 17.\u00a0Oktober 2023, Bangkok: Oberste Rechnungskontrollbeh\u00f6rde Thailand"}]},{"@type":"WebSite","@id":"https:\/\/intosaijournal.org\/#website","url":"https:\/\/intosaijournal.org\/","name":"INTOSAI Journal","description":"","publisher":{"@id":"https:\/\/intosaijournal.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intosaijournal.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/intosaijournal.org\/#organization","name":"INTOSAI Journal","url":"https:\/\/intosaijournal.org\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/","url":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","contentUrl":"https:\/\/intosai.nclud.com\/wp-content\/uploads\/2023\/04\/logo.png","width":736,"height":122,"caption":"INTOSAI Journal"},"image":{"@id":"https:\/\/intosaijournal.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/intosaijournal"]}]}},"_links":{"self":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/27646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry"}],"about":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/types\/journal-entry"}],"author":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":3,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/27646\/revisions"}],"predecessor-version":[{"id":28092,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-entry\/27646\/revisions\/28092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media\/26892"}],"wp:attachment":[{"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/media?parent=27646"}],"wp:term":[{"taxonomy":"journal-categories","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/journal-categories?post=27646"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/content-tags?post=27646"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/country?post=27646"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/region?post=27646"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/section?post=27646"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.intosaijournal.org\/de\/wp-json\/wp\/v2\/coauthors?post=27646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}